{"id":1018,"date":"2012-01-31T15:49:43","date_gmt":"2012-01-31T15:49:43","guid":{"rendered":"http:\/\/www.palmacentro.com\/blog\/?p=1018"},"modified":"2012-05-26T23:49:55","modified_gmt":"2012-05-26T21:49:55","slug":"13-magia-psicologica","status":"publish","type":"post","link":"https:\/\/www.palmacentro.com\/blog\/13-magia-psicologica\/","title":{"rendered":"13 &#8211; Magia psicol\u00f3gica"},"content":{"rendered":"\n<!-- Speed Sense for AdSense WordPress Plugin: https:\/\/wordpress.org\/plugins\/speed-sense\/ -->\n<div id=\"ssp0\" style=\"float:none;margin:10px 0 10px 0;text-align:center;max-width:728px;width:100%;\">\n<ins class=\"adsbygoogle\" id=\"adsgoogle0\" style=\"display: inline-block; width: 100%; height: 90px\"  data-ad-client=\"ca-pub-8118652243852059\" data-ad-slot=\"7814439714\"><\/ins><script>(adsbygoogle = window.adsbygoogle || []).push({});<\/script>\n<\/div>\n<p><a href=\"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/01\/13.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"1019\" data-permalink=\"https:\/\/www.palmacentro.com\/blog\/13-magia-psicologica\/attachment\/13\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/01\/13.jpg?fit=650%2C366&amp;ssl=1\" data-orig-size=\"650,366\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"13\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/01\/13.jpg?fit=650%2C366&amp;ssl=1\" class=\"aligncenter size-medium wp-image-1019\" title=\"13\" src=\"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/01\/13.jpg?resize=300%2C168\" alt=\"\" width=\"300\" height=\"168\" srcset=\"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/01\/13.jpg?resize=300%2C168&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/01\/13.jpg?resize=500%2C281&amp;ssl=1 500w, https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/01\/13.jpg?w=650&amp;ssl=1 650w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Los d\u00edas del <strong>2 al 4 de febrero<\/strong> a las <strong>21:00h<\/strong> y el <strong>5<\/strong> a las<strong> 19:00h<\/strong> podr\u00e9is ver la Magia de Joan Monse, con <strong>13, <\/strong>en el<strong> Teatre Principal de Palma<\/strong>.<\/p>\n<p>Despu\u00e9s del \u00e9xito de \u201cInc\u00f2gnita\u201d, Joan Monse nos presenta su nuevo espect\u00e1culo de <strong>Magia Psicol\u00f3gica<\/strong>. Una propuesta original y diferente donde nos plantea cuestiones como estas: \u201cNos dejamos influenciar mucho por los pensamientos de otras personas? Y, nuestros pensamientos negativos , como nos infuyen en nuestra vida? Eres una persona supersticiosa&#8230;?\u201d<\/p>\n<p style=\"text-align: center;\"><!--Error de YouTube: URL introducida incorrecta--><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los d\u00edas del 2 al 4 de febrero a las 21:00h y el 5 a las 19:00h podr\u00e9is ver la[&#8230;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[379,306,71,264,5601,229],"class_list":["post-1018","post","type-post","status-publish","format-standard","hentry","category-eventos-noticias","tag-379","tag-joan-carles-i","tag-magia","tag-matasuegras","tag-palma","tag-teatro-principal"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p1SDLj-gq","jetpack-related-posts":[{"id":5387,"url":"https:\/\/www.palmacentro.com\/blog\/disney-live-la-magia-de-mickey\/","url_meta":{"origin":1018,"position":0},"title":"DISNEY LIVE! \u2013 LA M\u00c1GIA DE MICKEY","author":"Ver\u00f3nica","date":"02\/11\/2012","format":false,"excerpt":"Disney Live! La Magia de Mickey, es la perfecta combinaci\u00f3n de los personajes favoritos de Disney junto a los ilusionistas profesionales, que transportar\u00e1n al p\u00fablico a un mundo en el que la magia adquiere un significado totalmente nuevo del 7 al 11 de noviembre en el Auditorium de Palma. Las\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/10\/Disney-Live-La-Magia-de-Mickey.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":5604,"url":"https:\/\/www.palmacentro.com\/blog\/spot-dijous-bo-de-inca\/","url_meta":{"origin":1018,"position":1},"title":"Spot Dijous Bo de Inca","author":"Ver\u00f3nica","date":"02\/11\/2012","format":false,"excerpt":"El spot de Dijous Bo 2012\u00a0 ser\u00e1 presentado este viernes 2 de noviembre en el Ayuntamiento de Inca\u00a0 y tiene como protagonista al actor y presentador Joan Monse, que sera el pregonero de este a\u00f1o. Dijous bo se celebra en Inca el d\u00eda 15\u00a0 de noviembre de 2012 tal y\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":773,"url":"https:\/\/www.palmacentro.com\/blog\/cuentos-para-sonar-el-musical\/","url_meta":{"origin":1018,"position":2},"title":"Cuentos para so\u00f1ar, el Musical","author":"Ver\u00f3nica","date":"04\/01\/2012","format":false,"excerpt":"Cuentos para so\u00f1ar, el musical es un recorrido en directo de los cuentos m\u00e1s famosos y las mejores producciones musicales. Podr\u00e9is disfrutar del musical el d\u00eda 7 a las 18:00h o tambi\u00e9n el d\u00eda 8 a las 12:00h y a las 18:00h, en el Teatre Principal de Palma. Disfruta de\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/01\/317.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":6052,"url":"https:\/\/www.palmacentro.com\/blog\/magia-en-el-trui-teatre\/","url_meta":{"origin":1018,"position":3},"title":"Magia en el Trui Teatre","author":"Ver\u00f3nica","date":"19\/12\/2012","format":false,"excerpt":"El 23 de diciembre a las 19h la Magia de Miguel Gavilan nos invadir\u00e1 en el Trui Teatre. Esto es magia es una recopilaci\u00f3n de las mejores ilusiones y efectos de la magia actual: apariciones, desapariciones, levitaciones, magia en tus manos, efectos llenos de sorpresas y risas ... Miguel Gavilan\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/12\/magia.jpeg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":6390,"url":"https:\/\/www.palmacentro.com\/blog\/magia-en-sa-botiga-de-buffons\/","url_meta":{"origin":1018,"position":4},"title":"Magia en Sa Botiga de Buffons","author":"Ver\u00f3nica","date":"28\/01\/2013","format":false,"excerpt":"El Mago Javier para los amigos, nos dejar\u00e1 con la boca abierta\u00a0 con sus juegos de cartas el mi\u00e9rcoles 30 de enero en\u00a0 Sa Botiga de Buffons, de la calle Valldargent, 29. de Palma. La actuaci\u00f3n empezar\u00e1 a las 22:30h con un precio de 8\u20ac.","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"javier magia","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2013\/01\/javier-magia.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":473,"url":"https:\/\/www.palmacentro.com\/blog\/el-mago-de-oz-el-musical\/","url_meta":{"origin":1018,"position":5},"title":"El Mago de Oz, El Musical","author":"Ver\u00f3nica","date":"20\/11\/2011","format":false,"excerpt":"Los d\u00edas 26 y 27 tendr\u00e1 lugar en el Auditorium de Palma el\u00a0 Musical del Mago de Oz. Las actuaciones ser\u00e1n, el 26 de noviembre a las 18:00h y el 27 a las 17:30h. El precio es de 20,54 \u20ac aprox. El 25 de agosto de 1939 tuvo lugar el\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2011\/11\/mago-oz.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2011\/11\/mago-oz.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2011\/11\/mago-oz.jpg?resize=525%2C300 1.5x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/posts\/1018","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/comments?post=1018"}],"version-history":[{"count":4,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/posts\/1018\/revisions"}],"predecessor-version":[{"id":3004,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/posts\/1018\/revisions\/3004"}],"wp:attachment":[{"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/media?parent=1018"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/categories?post=1018"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/tags?post=1018"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}