{"id":1505,"date":"2012-02-19T15:17:41","date_gmt":"2012-02-19T15:17:41","guid":{"rendered":"http:\/\/www.palmacentro.com\/blog\/?p=1505"},"modified":"2012-02-19T15:17:41","modified_gmt":"2012-02-19T15:17:41","slug":"protesta-en-palma-contra-la-reforma","status":"publish","type":"post","link":"https:\/\/www.palmacentro.com\/blog\/protesta-en-palma-contra-la-reforma\/","title":{"rendered":"Protesta en Palma contra la reforma"},"content":{"rendered":"<p><a href=\"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/02\/317.png1.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"1506\" data-permalink=\"https:\/\/www.palmacentro.com\/blog\/protesta-en-palma-contra-la-reforma\/317-png-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/02\/317.png1.jpg?fit=475%2C317&amp;ssl=1\" data-orig-size=\"475,317\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"317.png\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/02\/317.png1.jpg?fit=475%2C317&amp;ssl=1\" class=\"aligncenter size-medium wp-image-1506\" title=\"317.png\" src=\"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/02\/317.png1.jpg?resize=300%2C200\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/02\/317.png1.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/02\/317.png1.jpg?w=475&amp;ssl=1 475w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p><strong>Miles de personas<\/strong> han participado hoy,domingo 19 en la <strong>manifestaci\u00f3n\u00a0contra la reforma laboral<\/strong> celebrada en Palma.<br \/>\nLa reforma la citan como \u00abinjusta, ineficaz e in\u00fatil\u00bb, y los sindicatos convocantes CC.OO y UGT, pretenden convertir las calles de la capital balear en un clamor ante lo que consideran que supone una \u00abdesregulaci\u00f3n ideol\u00f3gica\u00bb y un retorno a las condiciones laborales del siglo XIX.<\/p>\n<p>Bajo el lema &#8216;No a la reforma laboral&#8217;\u00a0 miles de personas han partido desde Plaza Espa\u00f1a para recorrer las principales calles de Palma. Una de las 57 ciudades en las que se ha convocado esta manifestaci\u00f3n.<\/p>\n<p>Adem\u00e1s de la gente de\u00a0 los sindicatos tambi\u00e9n han asistido representantes del PSIB en el Parlament y dirigentes del PSM-IV-ExM y M\u00e9s per Menorca.<\/p>\n<p>Los sindicatos han indicado que la <strong>nueva modalidad de contrato indefinido<\/strong> que establece un <strong>periodo de prueba de 12 meses<\/strong> para empresas de menos de 50 trabajadores podr\u00eda contener \u00abelementos inconstitucionales\u00bb ya que supone una discriminaci\u00f3n al trabajador, apunt\u00f3 la secretaria general de CC.OO, Katiana Vicens.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Miles de personas han participado hoy,domingo 19 en la manifestaci\u00f3n\u00a0contra la reforma laboral celebrada en Palma. La reforma la citan[&#8230;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[508,510,506,504,5601,507,505,509],"class_list":["post-1505","post","type-post","status-publish","format-standard","hentry","category-eventos-noticias","tag-12-meses","tag-ccoo","tag-contrato-indefinido","tag-manifestacion","tag-palma","tag-prueba","tag-reforma-laboral","tag-ugt"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p1SDLj-oh","jetpack-related-posts":[{"id":2023,"url":"https:\/\/www.palmacentro.com\/blog\/huelga-general-29m-seguimiento\/","url_meta":{"origin":1505,"position":0},"title":"Huelga general 29M- Seguimiento","author":"Ver\u00f3nica","date":"29\/03\/2012","format":false,"excerpt":"Sobre las 21:00 h de ayer algo m\u00e1s medio centenar de personas se reun\u00eda en las inmediaciones de las sedes de los dos sindicatos mayoritarios de las Islas, UGT y CCOO, para participar en los primeros piquetes informativos de la huelga general contra la reforma laboral. Los piquetes informativos part\u00edan\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/03\/414.png-300x200.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":3290,"url":"https:\/\/www.palmacentro.com\/blog\/huelga-de-24-horas-en-hosteleria-el-20-de-julio\/","url_meta":{"origin":1505,"position":1},"title":"Huelga de 24 horas en hosteler\u00eda el 20 de julio","author":"Ver\u00f3nica","date":"08\/06\/2012","format":false,"excerpt":"Los sindicatos UGT y CCOO han aprobado convocar una huelga de 24 horas en el sector de la hosteler\u00eda de Baleares el pr\u00f3ximo 20 de julio, despu\u00e9s de que hayan fracasado las negociaciones con la patronal, tras dos reuniones celebradas este lunes y jueves en las que no se alcanz\u00f3\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/06\/hosteleria.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":4018,"url":"https:\/\/www.palmacentro.com\/blog\/gran-manifestacion-contra-los-recortes-del-govierno-en-palma\/","url_meta":{"origin":1505,"position":2},"title":"Gran manifestaci\u00f3n contra los recortes del Govierno en Palma","author":"Ver\u00f3nica","date":"20\/07\/2012","format":false,"excerpt":"M\u00e1s de 20.000 personas, 50.000 seg\u00fan han contabilizado los sindicatos, han protestado por el centro urbano de Palma contra los recortes del Gobierno anunciados la semana pasada. Gritos, banderas, bocinazos, pitidos y petardos han sonado en contra de las medidas del presidente del Gobierno, Mariano Rajoy y en contra del\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/07\/manifestacion.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":2863,"url":"https:\/\/www.palmacentro.com\/blog\/caravana-de-coches-por-sanidad-en-palma\/","url_meta":{"origin":1505,"position":3},"title":"Caravana de coches por Sanidad en Palma","author":"Ver\u00f3nica","date":"22\/05\/2012","format":false,"excerpt":"Esta ma\u00f1ana se celebra una caravana convocada por los sindicatos UGT y CCOO\u00a0 para enlazar de forma simb\u00f3lica los Hospitales Joan March y General, ya que estos ser\u00e1n cerrados por el plan de ajuste sanitario. La caravana ha salido a las 8:00h del hip\u00f3dromo de Palma y se han dirigido\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/05\/sanidad-recorte111.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":5734,"url":"https:\/\/www.palmacentro.com\/blog\/los-sindicatos-invitan-a-parados-y-trabajadores-a-participar-en-el-14n\/","url_meta":{"origin":1505,"position":4},"title":"Los Sindicatos invitan a parados y trabajadores a participar en el 14N","author":"Ver\u00f3nica","date":"13\/11\/2012","format":false,"excerpt":"Representantes de CCOO, UGT, STEI-i y USO han acudido hoy a la oficina del SOIB de Palma para informar a los desempleados de que pueden secundar la huelga general de ma\u00f1ana dejando de consumir y evitando realizar tr\u00e1mites administrativos, entre otras acciones. CCOO quiere que los parados tomen conciencia de\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/11\/HG14-N_todos_manos.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":1064,"url":"https:\/\/www.palmacentro.com\/blog\/un-centenar-de-trabajadores-de-spanair-se-concentran\/","url_meta":{"origin":1505,"position":5},"title":"Un centenar de trabajadores de Spanair se concentran","author":"Ver\u00f3nica","date":"02\/02\/2012","format":false,"excerpt":"Un centenar de trabajadores de Spanair han celebrado esta ma\u00f1ana una concentraci\u00f3n de protesta ante la sede del Call-center de la aerol\u00ednea en Can Pastilla y han reclamado que se atienda a su situaci\u00f3n tras el cierre de la compa\u00f1\u00eda. Los representantes de los sindicatos han constituido oficialmente el nuevo\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/02\/317.png-300x200.jpg?resize=350%2C200","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/posts\/1505","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/comments?post=1505"}],"version-history":[{"count":2,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/posts\/1505\/revisions"}],"predecessor-version":[{"id":1508,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/posts\/1505\/revisions\/1508"}],"wp:attachment":[{"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/media?parent=1505"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/categories?post=1505"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/tags?post=1505"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}