{"id":1680,"date":"2012-03-06T12:09:36","date_gmt":"2012-03-06T12:09:36","guid":{"rendered":"http:\/\/www.palmacentro.com\/blog\/?p=1680"},"modified":"2012-03-06T12:09:36","modified_gmt":"2012-03-06T12:09:36","slug":"bustamante-tour-mio-2012","status":"publish","type":"post","link":"https:\/\/www.palmacentro.com\/blog\/bustamante-tour-mio-2012\/","title":{"rendered":"Bustamante &#8211; Tour Mio 2012"},"content":{"rendered":"\n<!-- Speed Sense for AdSense WordPress Plugin: https:\/\/wordpress.org\/plugins\/speed-sense\/ -->\n<div id=\"ssp0\" style=\"float:none;margin:10px 0 10px 0;text-align:center;max-width:728px;width:100%;\">\n<ins class=\"adsbygoogle\" id=\"adsgoogle0\" style=\"display: inline-block; width: 100%; height: 90px\"  data-ad-client=\"ca-pub-8118652243852059\" data-ad-slot=\"7814439714\"><\/ins><script>(adsbygoogle = window.adsbygoogle || []).push({});<\/script>\n<\/div>\n<p><a href=\"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/03\/Sin-t%C3%ADtulo-1-copiar.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"1681\" data-permalink=\"https:\/\/www.palmacentro.com\/blog\/bustamante-tour-mio-2012\/sin-titulo-1-copiar\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/03\/Sin-t%C3%ADtulo-1-copiar.jpg?fit=499%2C306&amp;ssl=1\" data-orig-size=\"499,306\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"Sin t\u00edtulo-1 copiar\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/03\/Sin-t%C3%ADtulo-1-copiar.jpg?fit=499%2C306&amp;ssl=1\" class=\"aligncenter  wp-image-1681\" title=\"Sin t\u00edtulo-1 copiar\" src=\"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/03\/Sin-t%C3%ADtulo-1-copiar.jpg?resize=407%2C249\" alt=\"\" width=\"407\" height=\"249\" srcset=\"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/03\/Sin-t%C3%ADtulo-1-copiar.jpg?w=499&amp;ssl=1 499w, https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/03\/Sin-t%C3%ADtulo-1-copiar.jpg?resize=300%2C183&amp;ssl=1 300w\" sizes=\"auto, (max-width: 407px) 100vw, 407px\" \/><\/a><\/p>\n<p>El <strong>31 de marzo a las 21h en el Auditorium<\/strong> de Palma de Mallorca, Bustamante\u00a0en concierto con su<strong> Tour Mio<\/strong>.<\/p>\n<p><strong>Bustamante<\/strong> presenta \u00abM\u00edo\u00bb su s\u00e9ptimo trabajo discogr\u00e1fico en una gira por los principales Teatros de Espa\u00f1a, un directo de alto voltaje que combina los momentos m\u00e1s \u00edntimos de su carrera, demostrando que es uno de los grandes baladistas del panorama musical, y los m\u00e1s desenfrenados, un g\u00e9nero en el que el artista confirma que tambi\u00e9n sabe reinar con solvencia contrastada.\u00bb<\/p>\n<p>Disponibles entradas <strong>VIP<\/strong> consistentes en:<\/p>\n<p>&#8211; Acceso al recinto dos horas antes de apertura de puertas<br \/>\n&#8211; Localidades preferentes en primera y\/o segunda fila<br \/>\n&#8211; Acceso a las pruebas de sonido<br \/>\n&#8211; Meet&amp;Greet con David Bustamante<br \/>\n&#8211; Pack merchandising Tour Mio<br \/>\n&#8211; Coctel de bienvenida<\/p>\n<p><a href=\"http:\/\/www.servicaixa.com\/nav\/es\/musica\/palma_de_mallorca\/auditorium_de_palma_sala_magna_09r5\/bustamante_-tour_mio_2012\/index.html?CODIUSU=P019AP02\">Comprar entradas<\/a><\/p>\n<p style=\"text-align: center;\">\n","protected":false},"excerpt":{"rendered":"<p>El 31 de marzo a las 21h en el Auditorium de Palma de Mallorca, Bustamante\u00a0en concierto con su Tour Mio.[&#8230;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[72,689,51,621,687,688,5601,690,691],"class_list":["post-1680","post","type-post","status-publish","format-standard","hentry","category-eventos-noticias","tag-auditorium","tag-bustamante","tag-concierto","tag-entradas","tag-gira","tag-mio","tag-palma","tag-tour","tag-vip"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p1SDLj-r6","jetpack-related-posts":[{"id":8698,"url":"https:\/\/www.palmacentro.com\/blog\/bustamante-vivirenconcierto-el-25-de-abril-en-truiteatre\/","url_meta":{"origin":1680,"position":0},"title":"Bustamante #vivirenconcierto el 25 de Abril en TruiTeatre","author":"Ver\u00f3nica","date":"16\/04\/2015","format":false,"excerpt":"Bustamante presentar\u00e1 su \u00faltimo trabajo \u201cVIVIR\u201d el 25 de Abril a las 21h. en el Trui Teatre de Palma. VIVIR es el octavo \u00e1lbum de estudio con una colecci\u00f3n de 10 nuevos temas con \u201cFeliz\u201d como primer single. Las entradas Golden Ticket incluyen entrar a la prueba de sonido y\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"david_bustamante","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2015\/04\/david_bustamante_vivir-portada.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":566,"url":"https:\/\/www.palmacentro.com\/blog\/david-bisbal-gira-acustica\/","url_meta":{"origin":1680,"position":1},"title":"David Bisbal &#8211; Gira Ac\u00fastica","author":"Ver\u00f3nica","date":"29\/11\/2011","format":false,"excerpt":"El d\u00eda 8 de diciembre a las 21:00h en el Auditorium de Palma en concierto David Bisbal, que regresa despu\u00e9s del gran \u00e9xito obtenido durante los meses de Abril, Mayo y Junio con su Gira Ac\u00fastica.El precio de la entrada ronda los 49\u20ac. Una oportunidad extraordinaria para descubrir como nunca\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2011\/11\/david-bisbal.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2011\/11\/david-bisbal.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2011\/11\/david-bisbal.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2011\/11\/david-bisbal.jpg?resize=700%2C400 2x, https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2011\/11\/david-bisbal.jpg?resize=1050%2C600 3x"},"classes":[]},{"id":8741,"url":"https:\/\/www.palmacentro.com\/blog\/alejandro-sanz-el-12-de-agosto-en-la-plaza-de-toros-de-palma-con-su-gira-sirope\/","url_meta":{"origin":1680,"position":2},"title":"Alejandro Sanz el 12 de Agosto en la Plaza de Toros de Palma con su gira Sirope","author":"Ver\u00f3nica","date":"01\/06\/2015","format":false,"excerpt":"Concierto de Alejandro Sanz el 12 Agosto a las 22h en la Plaza De Toros de Palma presentando su gira Sirope. Uno de los artistas latinos con m\u00e1s \u00e9xito a nivel internacional que ya ha vendido m\u00e1s de 22 millones de discos a lo largo de su carrera. Adem\u00e1s de\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"alejandro sanz","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2015\/06\/alejandro-sanz1.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":6586,"url":"https:\/\/www.palmacentro.com\/blog\/alejandro-sanz-en-concierto-el-3-de-julio-en-mallorca\/","url_meta":{"origin":1680,"position":3},"title":"Alejandro Sanz en concierto el 3 de julio en Mallorca","author":"Ver\u00f3nica","date":"15\/06\/2013","format":false,"excerpt":"Alejandro Sanz visitar\u00e1 Mallorca el pr\u00f3ximo 3 de julio de 2013\u00a0 para dar un concierto en la Plaza de Toros de Palma a las 22h. Con su nueva gira, \"La M\u00fasica No Se Toca\", podremos disfrutar del cantante con su impactante y renovado directo, presentando los nuevos temas de su\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"gira alejandro sanz mallorca","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2013\/02\/gira-alejandro-sanz-mallorca.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2013\/02\/gira-alejandro-sanz-mallorca.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2013\/02\/gira-alejandro-sanz-mallorca.jpg?resize=525%2C300 1.5x"},"classes":[]},{"id":2351,"url":"https:\/\/www.palmacentro.com\/blog\/concierto-de-manuel-carrasco\/","url_meta":{"origin":1680,"position":4},"title":"Concierto de Manuel Carrasco","author":"Ver\u00f3nica","date":"27\/04\/2012","format":false,"excerpt":"Manuel Carrasco vuelve con su \u00faltimo trabajo HABLA, un trabajo sincero, lleno de mensajes de vida, recopilando historias cargadas de contrastes y dispuesto a sorprender... a emocionar. El concierto ser\u00e1 el dia 11 de mayo en el Auditorium de Palma a las 21:30h. En este nuevo \u00e1lbum Manuel ha tomado\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/04\/imagen274.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":2076,"url":"https:\/\/www.palmacentro.com\/blog\/diana-navarro-en-concierto\/","url_meta":{"origin":1680,"position":5},"title":"Diana Navarro en concierto","author":"Ver\u00f3nica","date":"07\/04\/2012","format":false,"excerpt":"En abril, concretamente el dia 13 a las 22:00h podremos escuchar en el Auditorium de Palma a Diana Navarro. Esta cantante malague\u00f1a se ha convertido en los \u00faltimos a\u00f1os en una de las principales voces de la copla. Desde que debutara en 1994 con la obtenci\u00f3n del Premio Especial Certamen\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/04\/Diana-Navarro-Flamenco-300x300.jpg?resize=350%2C200","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/posts\/1680","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/comments?post=1680"}],"version-history":[{"count":2,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/posts\/1680\/revisions"}],"predecessor-version":[{"id":1683,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/posts\/1680\/revisions\/1683"}],"wp:attachment":[{"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/media?parent=1680"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/categories?post=1680"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/tags?post=1680"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}