{"id":205,"date":"2011-10-04T11:31:53","date_gmt":"2011-10-04T11:31:53","guid":{"rendered":"http:\/\/www.palmacentro.com\/blog\/?p=205"},"modified":"2011-10-04T11:31:53","modified_gmt":"2011-10-04T11:31:53","slug":"muere-el-empresario-bernardo-ribasuno-de-los-pioneros-de-la-playa-de-palma","status":"publish","type":"post","link":"https:\/\/www.palmacentro.com\/blog\/muere-el-empresario-bernardo-ribasuno-de-los-pioneros-de-la-playa-de-palma\/","title":{"rendered":"Muere el empresario Bernardo Ribas,uno de los pioneros de la Playa de Palma"},"content":{"rendered":"\n<!-- Speed Sense for AdSense WordPress Plugin: https:\/\/wordpress.org\/plugins\/speed-sense\/ -->\n<div id=\"ssp0\" style=\"float:none;margin:10px 0 10px 0;text-align:center;max-width:728px;width:100%;\">\n<ins class=\"adsbygoogle\" id=\"adsgoogle0\" style=\"display: inline-block; width: 100%; height: 90px\"  data-ad-client=\"ca-pub-8118652243852059\" data-ad-slot=\"7814439714\"><\/ins><script>(adsbygoogle = window.adsbygoogle || []).push({});<\/script>\n<\/div>\n<p><a href=\"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2011\/10\/bernarribas.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"206\" data-permalink=\"https:\/\/www.palmacentro.com\/blog\/muere-el-empresario-bernardo-ribasuno-de-los-pioneros-de-la-playa-de-palma\/bernarribas\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2011\/10\/bernarribas.jpg?fit=500%2C220&amp;ssl=1\" data-orig-size=\"500,220\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"bernarribas\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2011\/10\/bernarribas.jpg?fit=500%2C220&amp;ssl=1\" class=\"aligncenter size-full wp-image-206\" title=\"bernarribas\" src=\"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2011\/10\/bernarribas.jpg?resize=500%2C220\" alt=\"\" width=\"500\" height=\"220\" srcset=\"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2011\/10\/bernarribas.jpg?w=500&amp;ssl=1 500w, https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2011\/10\/bernarribas.jpg?resize=300%2C132&amp;ssl=1 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n<p><strong>Bernardo Ribas Rub\u00ed<\/strong>, uno de los primeros empresarios hoteleros que centraron su actividad profesional en la <strong>Playa<\/strong><strong> de Palma<\/strong>, cuando la actividad tur\u00edstico hotelera de la zona se encontraba en su fase inicial, falleci\u00f3 ayer a los 89 a\u00f1os.<\/p>\n<p>Seg\u00fan informa la Federaci\u00f3n Hotelera de Mallorca en un comunicado, el <strong>funeral<\/strong> se celebrar\u00e1 este martes en la Iglesia de la Porci\u00fancula, en la Playa de Palma, a las 20:00 horas.<\/p>\n<p>Ribas naci\u00f3 en Santa Margalida pero realiz\u00f3 su trayectoria profesional en Playa de Palma, entre C\u00b4an Pastilla y El Arenal. Dedic\u00f3 toda su vida a la hosteler\u00eda.<\/p>\n<p>En el a\u00f1o <strong>1959<\/strong> construy\u00f3 el antiguo <strong>Hotel Diana<\/strong> de C\u00b4an Pastilla, posteriormente en el a\u00f1o 1961 abri\u00f3 el Hotel Ondina, a los que siguieron los Hoteles Mediod\u00eda e Hispania.<\/p>\n<p>&nbsp;<\/p>\n<p><em>Via<\/em> \/ Mallorcadiario<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bernardo Ribas Rub\u00ed, uno de los primeros empresarios hoteleros que centraron su actividad profesional en la Playa de Palma, cuando[&#8230;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[42,43,5601],"class_list":["post-205","post","type-post","status-publish","format-standard","hentry","category-eventos-noticias","tag-empresario","tag-muere","tag-palma"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p1SDLj-3j","jetpack-related-posts":[{"id":7488,"url":"https:\/\/www.palmacentro.com\/blog\/palma-365-sabado-20-y-domingo-21\/","url_meta":{"origin":205,"position":0},"title":"Palma 365, s\u00e1bado 20 y domingo 21","author":"Ver\u00f3nica","date":"19\/07\/2013","format":false,"excerpt":"Para el fin de semana, 20 y 21 de julio\u00a0Palma 365 no cierra. Aqu\u00ed ten\u00e9is el programa Palma con las actividades. Taller infantil medioambiental en la playa de Can Pere Antoni y que tiene continuidad el domingo, en la playa de Ciudad Jard\u00edn. La tercera jornada de acuatl\u00f3n Ciudad de\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"sube turismo","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/10\/sube-turismo-210x300.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":3380,"url":"https:\/\/www.palmacentro.com\/blog\/obsession-beach-party-en-la-playa-de-ca%c2%b4n-pastilla\/","url_meta":{"origin":205,"position":1},"title":"Obsession Beach Party en la Playa de Ca\u00b4n Pastilla","author":"Ver\u00f3nica","date":"12\/06\/2012","format":false,"excerpt":"El domingo 17 de Junio ven a disfrutar de la fiesta en la playa de Can Pastilla de 11:00h a 23:00h IMPRESCINDIBLE IR DE AZUL!! Pasa un domingo diferente en la playa de Can Pastilla junto al club n\u00e1utico, y disfruta de la mejor entrada del verano sol, playa, carpas,\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/06\/obsession_beach_party_mallorca.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":4746,"url":"https:\/\/www.palmacentro.com\/blog\/playa-de-palma-como-destino-turistico-digital\/","url_meta":{"origin":205,"position":2},"title":"Playa de Palma como destino turistico digital","author":"Ver\u00f3nica","date":"07\/09\/2012","format":false,"excerpt":"La Playa de Palma se convertir\u00e1 en un \"destino digital e inteligente\" gracias a una serie de actuaciones tecnol\u00f3gicas, seg\u00fan prev\u00e9 un acuerdo firmado entre la consejer\u00eda de Turismo y Deporte de Baleares y la sociedad estatal Segittur. Dicho convenio ha sido firmado por el consejero de Turismo y presidente\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/09\/acuerdo-palma-digital.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":2139,"url":"https:\/\/www.palmacentro.com\/blog\/palma-presenta-su-nueva-marca-turistica\/","url_meta":{"origin":205,"position":3},"title":"Palma presenta su nueva marca tur\u00edstica","author":"Ver\u00f3nica","date":"05\/04\/2012","format":false,"excerpt":"The Atomic Idea, con el proyecto PALMACOR 2012 es la ganadora del concurso con la imagen de un coraz\u00f3n que expresa \"pasi\u00f3n\" por Palma Mateo Isern: \"La iniciativa nace por la necesidad de crear una marca nueva, que distinga un nuevo producto, m\u00e1s all\u00e1 del sol y playa\" \u00c1lvaro Gij\u00f3n:\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/04\/palmalogo.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":3343,"url":"https:\/\/www.palmacentro.com\/blog\/anni-b-sweet-son-the-holy-ghosts-en-palma-de-mallorca\/","url_meta":{"origin":205,"position":4},"title":"Anni B Sweet, Son &#038; The Holy Ghosts en Palma de Mallorca","author":"Ver\u00f3nica","date":"14\/06\/2012","format":false,"excerpt":"El d\u00eda 21 de junio se celebra el d\u00eda de la m\u00fasica a nivel mundial y Palma acoger\u00e1 este a\u00f1o a la malague\u00f1a Anni B Sweet y a la banda mallorquina Son & The Holy Ghosts en Es Gremi. El concierto patrocinado por Bodegas Ribas ser\u00e1 en la renovada Sala\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/06\/598876_396800697022674_2029051793_n.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":5105,"url":"https:\/\/www.palmacentro.com\/blog\/xv-semana-internacional-de-ciclismo-masters\/","url_meta":{"origin":205,"position":5},"title":"XV Semana Internacional de Ciclismo Masters","author":"Ver\u00f3nica","date":"02\/10\/2012","format":false,"excerpt":"Los d\u00edas del 8 al 13 de octubre se celebra la XV Semana Internacional de Ciclismo Masters en Mallorca. La XVIII edici\u00f3n de la Copa de Europa de Masters llega a la Playa de Palma el d\u00eda 8 de octubre, con el tradicional circuito urbano de 11,5 kil\u00f3metros. La Semana\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/10\/semana-internacional-ciclismo.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/10\/semana-internacional-ciclismo.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/10\/semana-internacional-ciclismo.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/10\/semana-internacional-ciclismo.jpg?resize=700%2C400 2x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/posts\/205","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/comments?post=205"}],"version-history":[{"count":1,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/posts\/205\/revisions"}],"predecessor-version":[{"id":207,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/posts\/205\/revisions\/207"}],"wp:attachment":[{"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/media?parent=205"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/categories?post=205"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/tags?post=205"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}