{"id":2735,"date":"2012-05-14T10:27:47","date_gmt":"2012-05-14T10:27:47","guid":{"rendered":"http:\/\/www.palmacentro.com\/blog\/?p=2735"},"modified":"2012-05-14T10:30:24","modified_gmt":"2012-05-14T10:30:24","slug":"mallorca-rocks-hotel","status":"publish","type":"post","link":"https:\/\/www.palmacentro.com\/blog\/mallorca-rocks-hotel\/","title":{"rendered":"Mallorca Rocks Hotel"},"content":{"rendered":"\n<!-- Speed Sense for AdSense WordPress Plugin: https:\/\/wordpress.org\/plugins\/speed-sense\/ -->\n<div id=\"ssp0\" style=\"float:none;margin:10px 0 10px 0;text-align:center;max-width:728px;width:100%;\">\n<ins class=\"adsbygoogle\" id=\"adsgoogle0\" style=\"display: inline-block; width: 100%; height: 90px\"  data-ad-client=\"ca-pub-8118652243852059\" data-ad-slot=\"7814439714\"><\/ins><script>(adsbygoogle = window.adsbygoogle || []).push({});<\/script>\n<\/div>\n<p>Con id\u00e9ntica filosof\u00eda que el Ibiza Rocks Hotel y en la f\u00f3rmula que combina m\u00fasica en directo, buen tiempo y un alojamiento de dise\u00f1o juvenil y a buen precio, lanz\u00e1bamos el pasado a\u00f1o 2010 en Magalluf el incre\u00edble Mallorca Rocks Hotel.<\/p>\n<p>Recuerda que todas las reservas en Mallorca Rocks Hotel incluyen una entrada para el concierto semanal que suceder\u00e1 cada martes*.<\/p>\n<p style=\"text-align: center;\"><!--Error de YouTube: URL introducida incorrecta--><\/p>\n<p style=\"text-align: center;\"><!--more--><\/p>\n<p>Aunque tienes que verlo t\u00fa mismo, el hotel es un enorme edificio compuesto por 12 bloques que rodean una inmensa piscina de 85 metros en un \u00e1rea en el que suceden los eventos m\u00e1s divertidos del verano balear que incluyen no s\u00f3lo conciertos de bandas de nombre internacional, sino tambi\u00e9n fiestas con geniales deejays.<\/p>\n<p><a href=\"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/05\/MR_lineup_takeover2.png\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"2736\" data-permalink=\"https:\/\/www.palmacentro.com\/blog\/mallorca-rocks-hotel\/mr_lineup_takeover2\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/05\/MR_lineup_takeover2.png?fit=840%2C557&amp;ssl=1\" data-orig-size=\"840,557\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"MR_lineup_takeover2\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/05\/MR_lineup_takeover2.png?fit=840%2C557&amp;ssl=1\" class=\"aligncenter  wp-image-2736\" title=\"MR_lineup_takeover2\" src=\"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/05\/MR_lineup_takeover2.png?resize=705%2C467\" alt=\"\" width=\"705\" height=\"467\" srcset=\"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/05\/MR_lineup_takeover2.png?w=840&amp;ssl=1 840w, https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/05\/MR_lineup_takeover2.png?resize=300%2C198&amp;ssl=1 300w\" sizes=\"auto, (max-width: 705px) 100vw, 705px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con id\u00e9ntica filosof\u00eda que el Ibiza Rocks Hotel y en la f\u00f3rmula que combina m\u00fasica en directo, buen tiempo y[&#8230;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[1737,1732,1735,1736,1726,1729,1731,1722,1738,1728,108,1734,1730,1725,1723,1727,1724,1733],"class_list":["post-2735","post","type-post","status-publish","format-standard","hentry","category-eventos-noticias","tag-alojamiento","tag-axwell","tag-azelia-banks","tag-directo","tag-ed-sheeran","tag-kaiser-chiefs","tag-kasabian","tag-mallorca-rocks","tag-martes","tag-maverick-sabre","tag-musica","tag-paolo-nutini","tag-plan-b","tag-rocks-hotel","tag-summer-2012","tag-the-milk","tag-tuesdays-at-mallorca","tag-two-door-cinema-club"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p1SDLj-I7","jetpack-related-posts":[{"id":7239,"url":"https:\/\/www.palmacentro.com\/blog\/mallorca-rocks-2013\/","url_meta":{"origin":2735,"position":0},"title":"Mallorca Rocks 2013","author":"Ver\u00f3nica","date":"04\/06\/2013","format":false,"excerpt":"Buen tiempo, alojamiento y 16 semanas de fant\u00e1sticas actuaciones bajo las estrellas de la Baleares con los conciertos y Dj\u2019s m\u00e1s solicitados del planeta, todo ello lo encontrar\u00e1s en Mallorca Rocks. Os adjunto un v\u00eddeo y el programa de conciertos. Junio 2013 Mallorca Rocks con Jake Bugg, 4 Junio 2013\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"mallorca rocks","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2013\/06\/mallorca-rocks.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":8507,"url":"https:\/\/www.palmacentro.com\/blog\/mallorca-rocks-2014\/","url_meta":{"origin":2735,"position":1},"title":"Mallorca Rocks 2014","author":"Ver\u00f3nica","date":"10\/05\/2014","format":false,"excerpt":"Pronto llega un a\u00f1o m\u00e1s del Mallorca Rocks Festival junto al buen tiempo, alojamiento y unas semanas de fant\u00e1sticas actuaciones bajo las estrellas de la Baleares con los conciertos y Dj\u2019s m\u00e1s solicitados del planeta. Os adjunto el v\u00eddeo presentaci\u00f3n y el programa de todos los conciertos que se dar\u00e1n.\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"mallorca rocks","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2014\/05\/mallorca-rocks.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":4466,"url":"https:\/\/www.palmacentro.com\/blog\/wonderbrass-actuara-en-el-blue-jazz-club-del-hotel-saratoga\/","url_meta":{"origin":2735,"position":2},"title":"WonderBrass actuar\u00e1 en el Blue Jazz Club del Hotel Saratoga","author":"Ver\u00f3nica","date":"21\/08\/2012","format":false,"excerpt":"El jueves 23 de agosto a partir de las 22h, WonderBrass actuar\u00e1 en el Blue Jazz Club del Hotel Saratoga. Carcajadas a ritmo de swing. Wonderbrass nace en la isla de Mallorca en 1999, sus cuatro miembros: N\u00e9stor Casas (trompeta y voz), Nacho Vegas (saxo tenor, clarinete, guitarra, voz), Didac\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/08\/jazzclub-54_3.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":7577,"url":"https:\/\/www.palmacentro.com\/blog\/tramuntana-rocks-festival-el-3-de-agsoto\/","url_meta":{"origin":2735,"position":3},"title":"Tramuntana Rocks Festival el 3 de agosto","author":"Ver\u00f3nica","date":"01\/08\/2013","format":false,"excerpt":"S\u00e1bado 3 de agosto a las 20h, en la Pista de Tenis de Son Quint de Esporles se celebra el Tramuntana Rocks Festival. 2 escenarios de m\u00fasica en vivo y 100% producto local. Bandas: Niels Jensen - Sadie Pickering - Tony & The Vicious - Tramuntana Abduction - The Wheels\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"tramuntana","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2013\/08\/tramuntana.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":6906,"url":"https:\/\/www.palmacentro.com\/blog\/mallorca-saxophone-festival-del-22-al-27-de-marzo\/","url_meta":{"origin":2735,"position":4},"title":"Mallorca Saxophone Festival del 22 al 27 de marzo","author":"Ver\u00f3nica","date":"22\/03\/2013","format":false,"excerpt":"La 5\u00aa edici\u00f3n del Mallorca Saxophone Festival ser\u00e1 del 22 al 27 de marzo, organitzada por la Associaci\u00f3 de Saxofonistes de les Illes Balears, con la colaboraci\u00f3n del Institut d\u2019Estudis Bale\u00e0rics (IEB). Aqu\u00ed est\u00e1 la programaci\u00f3n de los conciertos del festival de saxof\u00f3n de Mallorca que se realizar\u00e1n en diversos\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"saxophonemallorca2013","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2013\/03\/saxophonemallorca20131.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":3622,"url":"https:\/\/www.palmacentro.com\/blog\/flesh-art-fair-palma-de-mallorca-2012\/","url_meta":{"origin":2735,"position":5},"title":"Flesh Art Fair Palma de Mallorca 2012","author":"Ver\u00f3nica","date":"29\/06\/2012","format":false,"excerpt":"El Hotel Palau Sa Font, edificio hist\u00f3rico del s. XVI situado en el casco antiguo de Palma de Mallorca, acoger\u00e1 del 27 al 29 de julio la primera edici\u00f3n de Flesh Art Fair. En sus 20 habitaciones se exhibir\u00e1n proyectos de numerosos artistas visuales que ofrecer\u00e1n una muestra del arte\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/06\/BANNER_02.jpg?resize=350%2C200","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/posts\/2735","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/comments?post=2735"}],"version-history":[{"count":6,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/posts\/2735\/revisions"}],"predecessor-version":[{"id":2757,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/posts\/2735\/revisions\/2757"}],"wp:attachment":[{"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/media?parent=2735"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/categories?post=2735"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/tags?post=2735"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}