{"id":3193,"date":"2012-06-04T12:21:41","date_gmt":"2012-06-04T10:21:41","guid":{"rendered":"http:\/\/www.palmacentro.com\/blog\/?p=3193"},"modified":"2012-06-04T13:02:55","modified_gmt":"2012-06-04T11:02:55","slug":"este-utltimo-mes-baleares-lidera-en-la-bajada-del-paro","status":"publish","type":"post","link":"https:\/\/www.palmacentro.com\/blog\/este-utltimo-mes-baleares-lidera-en-la-bajada-del-paro\/","title":{"rendered":"Este \u00faltimo mes Baleares lidera en la bajada del paro"},"content":{"rendered":"<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"3194\" data-permalink=\"https:\/\/www.palmacentro.com\/blog\/este-utltimo-mes-baleares-lidera-en-la-bajada-del-paro\/entrevista\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/06\/entrevista.jpg?fit=325%2C487&amp;ssl=1\" data-orig-size=\"325,487\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"entrevista\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/06\/entrevista.jpg?fit=325%2C487&amp;ssl=1\" class=\"alignleft size-full wp-image-3194\" title=\"entrevista\" src=\"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/06\/entrevista.jpg?resize=139%2C209\" alt=\"\" width=\"139\" height=\"209\" srcset=\"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/06\/entrevista.jpg?w=325&amp;ssl=1 325w, https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/06\/entrevista.jpg?resize=200%2C300&amp;ssl=1 200w\" sizes=\"auto, (max-width: 139px) 100vw, 139px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Seg\u00fan los datos hechos p\u00fablicos por el Ministerio de Empleo y Seguridad Social, Baleares encabeza la bajada del paro que se ha registrado en el mes de mayo sobre las 15 comunidades aut\u00f3nomas. El paro ha descendido un\u00a0 8,12 % al haber 7.293\u00a0 desempleados menos Baleares. En el mes pasado, el n\u00famero de parados en Baleares era de 82.514 personas, pero a pesar de que el paro ha bajado en mayo, en los \u00faltimos doce meses el n\u00famero de parados ha subido en 6.742.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Seg\u00fan los datos hechos p\u00fablicos por el Ministerio de Empleo y Seguridad Social, Baleares encabeza la bajada del paro[&#8230;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[994,169,2082,2083,1348,36,1214],"class_list":["post-3193","post","type-post","status-publish","format-standard","hentry","category-eventos-noticias","tag-baja","tag-baleares","tag-descendido","tag-empleo","tag-mayo","tag-paro","tag-trabajo"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p1SDLj-Pv","jetpack-related-posts":[{"id":3759,"url":"https:\/\/www.palmacentro.com\/blog\/baleares-encabeza-la-bajada-del-paro-con-un-635-menos\/","url_meta":{"origin":3193,"position":0},"title":"Baleares encabeza la bajada del paro con un 6,35% menos","author":"Ver\u00f3nica","date":"03\/07\/2012","format":false,"excerpt":"Baleares es la comunidad aut\u00f3noma que ha tenido mayor descenso del paro en el mes de junio, con 5.237 desempleados menos, lo que supone una ca\u00edda del 6,35% en relaci\u00f3n al mes anterior, frente al descenso del 2,10% registrado a nivel nacional, seg\u00fan ha informado el Ministerio de Empleo y\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/07\/Caida_Tasa_De_Paro_Abril_2012.jpeg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":5635,"url":"https:\/\/www.palmacentro.com\/blog\/9-747-parados-mas-en-octubre-de-baleares\/","url_meta":{"origin":3193,"position":1},"title":"9.747 parados m\u00e1s en octubre de Baleares","author":"Ver\u00f3nica","date":"06\/11\/2012","format":false,"excerpt":"Seg\u00fan inform\u00f3 el Ministerio de Trabajo e Inmigraci\u00f3n, Baleares ha subido el numero de parados en 9.474 desempleados m\u00e1s respecto al mes de septiembre. Estos datos suponen un incremento de parados de un 12,20%. Por lo que la cifra total de desempleados en las oficinas del Servei d\u2019Ocupaci\u00f3 de les\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/11\/desempleo-baleares.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":4149,"url":"https:\/\/www.palmacentro.com\/blog\/baleares-aumenta-su-ocupacion-en-60-400-personas\/","url_meta":{"origin":3193,"position":2},"title":"Baleares aumenta su ocupaci\u00f3n en 60.400 personas","author":"Ver\u00f3nica","date":"27\/07\/2012","format":false,"excerpt":"Balears es la comunidad aut\u00f3noma que mas a bajado la tasa de paro al contratar a 60.400 personas y al descender\u00a0 a 33.700 parados, seguida de Madrid que ha contratado 7.500 personas. Seg\u00fan el Instituto Nacional de Estad\u00edstica el n\u00famero de trabajadores en Baleares ha subido a los 481.600 empleados,\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/07\/Caida_Tasa_De_Paro_Abril_20121.jpeg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":2602,"url":"https:\/\/www.palmacentro.com\/blog\/en-abril-el-numero-de-parados-registrados-desciende-en-6-632-personas\/","url_meta":{"origin":3193,"position":3},"title":"En abril el n\u00famero de parados registrados desciende en 6.632 personas","author":"Ver\u00f3nica","date":"04\/05\/2012","format":false,"excerpt":"Los datos de los Servicios P\u00fablicos de Empleo del conjunto de las comunidades aut\u00f3nomas correspondientes al mes de abril registran un descenso de 6.632 personas, lo que supone una reducci\u00f3n del (0,14%) respecto al mes anterior. En total el paro registrado se ha situado en 4.744.235 personas. Por sectores econ\u00f3micos,\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/05\/TN_7N0A7599-300x200.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":2023,"url":"https:\/\/www.palmacentro.com\/blog\/huelga-general-29m-seguimiento\/","url_meta":{"origin":3193,"position":4},"title":"Huelga general 29M- Seguimiento","author":"Ver\u00f3nica","date":"29\/03\/2012","format":false,"excerpt":"Sobre las 21:00 h de ayer algo m\u00e1s medio centenar de personas se reun\u00eda en las inmediaciones de las sedes de los dos sindicatos mayoritarios de las Islas, UGT y CCOO, para participar en los primeros piquetes informativos de la huelga general contra la reforma laboral. Los piquetes informativos part\u00edan\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/03\/414.png-300x200.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":3655,"url":"https:\/\/www.palmacentro.com\/blog\/proyecto-hombre-alerta-de-que-el-consumo-de-droga-aumenta-con-la-crisis\/","url_meta":{"origin":3193,"position":5},"title":"Proyecto Hombre alerta de que el consumo de droga aumenta con la crisis","author":"Ver\u00f3nica","date":"26\/06\/2012","format":false,"excerpt":"El Proyecto Hombre de Baleares ha registrado un aumento de las personas tratadas por consumo de hero\u00edna y por alcoholismo desde 2008, a\u00f1o en que comenz\u00f3 la crisis, mientras que la coca\u00edna se mantiene como principal droga de referencia. El informe que se ha difundido con motivo de la celebraci\u00f3n\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/06\/drogas.jpg?resize=350%2C200","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/posts\/3193","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/comments?post=3193"}],"version-history":[{"count":3,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/posts\/3193\/revisions"}],"predecessor-version":[{"id":3196,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/posts\/3193\/revisions\/3196"}],"wp:attachment":[{"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/media?parent=3193"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/categories?post=3193"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/tags?post=3193"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}