{"id":3396,"date":"2012-06-13T14:19:52","date_gmt":"2012-06-13T12:19:52","guid":{"rendered":"http:\/\/www.palmacentro.com\/blog\/?p=3396"},"modified":"2012-06-15T19:24:17","modified_gmt":"2012-06-15T17:24:17","slug":"el-grup-de-teatre-jove-de-cala-dor-nos-presenta-un-mal-trago","status":"publish","type":"post","link":"https:\/\/www.palmacentro.com\/blog\/el-grup-de-teatre-jove-de-cala-dor-nos-presenta-un-mal-trago\/","title":{"rendered":"El grup de teatre jove de Cala d&#8217;Or nos presenta Un mal trago"},"content":{"rendered":"\n<!-- Speed Sense for AdSense WordPress Plugin: https:\/\/wordpress.org\/plugins\/speed-sense\/ -->\n<div id=\"ssp0\" style=\"float:none;margin:10px 0 10px 0;text-align:center;max-width:728px;width:100%;\">\n<ins class=\"adsbygoogle\" id=\"adsgoogle0\" style=\"display: inline-block; width: 100%; height: 90px\"  data-ad-client=\"ca-pub-8118652243852059\" data-ad-slot=\"7814439714\"><\/ins><script>(adsbygoogle = window.adsbygoogle || []).push({});<\/script>\n<\/div>\n<p><a href=\"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/06\/521502_10150851915136091_2071024000_n.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"3504\" data-permalink=\"https:\/\/www.palmacentro.com\/blog\/el-grup-de-teatre-jove-de-cala-dor-nos-presenta-un-mal-trago\/521502_10150851915136091_2071024000_n\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/06\/521502_10150851915136091_2071024000_n.jpg?fit=508%2C720&amp;ssl=1\" data-orig-size=\"508,720\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"un mal trago\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/06\/521502_10150851915136091_2071024000_n.jpg?fit=508%2C720&amp;ssl=1\" class=\"aligncenter  wp-image-3504\" title=\"un mal trago\" src=\"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/06\/521502_10150851915136091_2071024000_n.jpg?resize=395%2C560\" alt=\"\" width=\"395\" height=\"560\" srcset=\"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/06\/521502_10150851915136091_2071024000_n.jpg?w=508&amp;ssl=1 508w, https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/06\/521502_10150851915136091_2071024000_n.jpg?resize=211%2C300&amp;ssl=1 211w\" sizes=\"auto, (max-width: 395px) 100vw, 395px\" \/><\/a><\/p>\n<p>Durante los d\u00edas<strong> 16 y 17 a las 19:00h en el Teatro Principal de Santany\u00ed presenta UN MAL TRAGO.<\/strong><\/p>\n<p>Sinopsis: J\u00f3venes y alcohol son los ingredientes de esta historia\u00a0 tr\u00e0gico-comica que os queremos contar. Un fin de semana para pasarlo bien, amigos, coche, fiesta, alcohol y las posibles consecuencias de esta combinaci\u00f3n. Juan, nuestro protagonista, tiene 18 a\u00f1os y muchas ganas de ir de fiesta, aunque su novia Roc\u00edo quiere quedarse para dar una vuelta, \u00e9l toma la decisi\u00f3n de ir con los amigos de marcha.<!--more--><\/p>\n<p>Int\u00e9rpretes: Noelia S\u00e1nchez, Dar\u00edo S\u00e1nchez, Paula Gilabert, M\u00aa \u00c1ngeles Garrones, Adri\u00e1n Campoy, Carlos S\u00e1nchez, Noelia Guti\u00e9rrez, Sandra Uroz, Rosal\u00eda Losa, Estela Calle, Antoni Thomas Barrilado, Irene Aparicio, Nasti Schaffernich.<br \/>\nDirecci\u00f3n: Oliver Romero<br \/>\nOrganizaci\u00f3n: Juventud Ayto. Santany\u00ed<\/p>\n<p>ENTRADA GRATUITA<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante los d\u00edas 16 y 17 a las 19:00h en el Teatro Principal de Santany\u00ed presenta UN MAL TRAGO. Sinopsis:[&#8230;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[1455,790,2303,2304,37,247,18,229,2302],"class_list":["post-3396","post","type-post","status-publish","format-standard","hentry","category-eventos-noticias","tag-entrada","tag-gratis","tag-gurp","tag-jove","tag-mallorca","tag-santanyi","tag-teatro","tag-teatro-principal","tag-un-mal-trago"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p1SDLj-SM","jetpack-related-posts":[{"id":5652,"url":"https:\/\/www.palmacentro.com\/blog\/tengo-ganas-de-ti-en-el-teatro-principal-de-santanyi\/","url_meta":{"origin":3396,"position":0},"title":"Tengo ganas de ti en el Teatro Principal de Santany\u00ed","author":"Ver\u00f3nica","date":"07\/11\/2012","format":false,"excerpt":"","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/11\/teatro-principal.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":5827,"url":"https:\/\/www.palmacentro.com\/blog\/fiestas-de-sant-andreu-de-santanyi\/","url_meta":{"origin":3396,"position":1},"title":"Fiestas de Sant Andreu de Santany\u00ed","author":"Ver\u00f3nica","date":"20\/11\/2012","format":false,"excerpt":"Este jueves d\u00eda 22 de noviembre dar\u00e1n comienzo las Fiestas de Sant Andreu 2012 de Santany\u00ed. Durante las fiestas podr\u00e9is ver exposiciones, concierto de la Orquesta Sinf\u00f3nica, teatro, gigantes, payasos, entre otros. Aqu\u00ed os adjunto el programa que durar\u00e1 hasta el 26 de diciembre. Sant Andreu 2012. \u00a0","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/11\/sant-andreu.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":5845,"url":"https:\/\/www.palmacentro.com\/blog\/donde-ir-este-fin-de-semana-2324-y-25-de-noviembre\/","url_meta":{"origin":3396,"position":2},"title":"\u00bfD\u00f3nde ir este fin de semana? 23,24 y 25 de noviembre","author":"Ver\u00f3nica","date":"23\/11\/2012","format":false,"excerpt":"\u00bfQue tenemos para este fin de semana? Como siempre hay opciones para todos los gustos y edades, as\u00ed como de precios. Fira de l'Esclata-sang i la Muntanya en Manacor de la Vall Icepark, la pista de hielo abre sus puertas Fiestas Sant Andreu de Santany\u00ed Concierto de Rosana Las Noches\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/11\/varios-copiar.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/11\/varios-copiar.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/11\/varios-copiar.jpg?resize=525%2C300 1.5x"},"classes":[]},{"id":8798,"url":"https:\/\/www.palmacentro.com\/blog\/grease-el-musical-en-el-teatro-principal-de-palma\/","url_meta":{"origin":3396,"position":3},"title":"Grease, el Musical en el Teatro Principal de Palma","author":"Ver\u00f3nica","date":"08\/09\/2015","format":false,"excerpt":"Del 17 al 20 de Septiembre Baleartmusic presenta el Musical de Grease en el Teatro Principal de Palma. Grease es una obra donde observamos un estilo de vida y la m\u00fasica de los a\u00f1os 50, donde su gran \u00e9xito fue gracias a la pel\u00edcula protagonizada por\u00a0Olivia Newton John y John\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2015\/09\/grease-grup-6384.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2015\/09\/grease-grup-6384.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2015\/09\/grease-grup-6384.jpg?resize=525%2C300 1.5x"},"classes":[]},{"id":3910,"url":"https:\/\/www.palmacentro.com\/blog\/fiestas-de-la-mare-de-deu-del-carme-cala-figuera\/","url_meta":{"origin":3396,"position":4},"title":"Fiestas de la Mare de D\u00e9u del Carme &#8211; Cala Figuera","author":"Ver\u00f3nica","date":"12\/07\/2012","format":false,"excerpt":"Programa de la fiesta en honor a la Mare de D\u00e9u del Carme del 2012 en Cala Figuera, Santany\u00ed. 14 DE JULIO 9:30h Concentraci\u00f3n de participantes de la\u00a0 1\u00aa cursa con bicicleta de monta\u00f1a para ni\u00f1os de\u00a0 4 a 14 a\u00f1os. El recorrido sera por en n\u00facleo de Cala Figuera.\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/07\/Captura.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":2728,"url":"https:\/\/www.palmacentro.com\/blog\/carmina-burana-magica-en-el-teatro-principal-de-palma\/","url_meta":{"origin":3396,"position":5},"title":"Carmina Burana M\u00e1gica en el Teatro Principal de Palma","author":"Ver\u00f3nica","date":"25\/05\/2012","format":false,"excerpt":"La Fundaci\u00f3n Teatro Principal de Palma presenta Carmina Burana M\u00e1gica el d\u00eda 2 de junio a las 21:00h. Carl Orff se basa en una colecci\u00f3n de cantos goliardos de los s.XII-XIII conservados en un c\u00f3dice encontrado en Beuern, Baviera. En estos poemas, escritos en lat\u00edn, franc\u00e9s y alem\u00e1n,se construyen elogios\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/05\/339carmina2012.jpg?resize=350%2C200","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/posts\/3396","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/comments?post=3396"}],"version-history":[{"count":3,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/posts\/3396\/revisions"}],"predecessor-version":[{"id":3505,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/posts\/3396\/revisions\/3505"}],"wp:attachment":[{"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/media?parent=3396"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/categories?post=3396"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/tags?post=3396"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}