{"id":4034,"date":"2012-07-21T12:26:40","date_gmt":"2012-07-21T10:26:40","guid":{"rendered":"http:\/\/www.palmacentro.com\/blog\/?p=4034"},"modified":"2012-07-21T12:28:25","modified_gmt":"2012-07-21T10:28:25","slug":"se-paran-las-obras-del-palacio-de-congresos","status":"publish","type":"post","link":"https:\/\/www.palmacentro.com\/blog\/se-paran-las-obras-del-palacio-de-congresos\/","title":{"rendered":"Se paran las obras del Palacio de Congresos"},"content":{"rendered":"\n<!-- Speed Sense for AdSense WordPress Plugin: https:\/\/wordpress.org\/plugins\/speed-sense\/ -->\n<div id=\"ssp0\" style=\"float:none;margin:10px 0 10px 0;text-align:center;max-width:728px;width:100%;\">\n<ins class=\"adsbygoogle\" id=\"adsgoogle0\" style=\"display: inline-block; width: 100%; height: 90px\"  data-ad-client=\"ca-pub-8118652243852059\" data-ad-slot=\"7814439714\"><\/ins><script>(adsbygoogle = window.adsbygoogle || []).push({});<\/script>\n<\/div>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"4035\" data-permalink=\"https:\/\/www.palmacentro.com\/blog\/se-paran-las-obras-del-palacio-de-congresos\/palau-congresos\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/07\/palau-congresos.jpg?fit=750%2C465&amp;ssl=1\" data-orig-size=\"750,465\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;6.3&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;P 45&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1124966718&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;80&quot;,&quot;iso&quot;:&quot;100&quot;,&quot;shutter_speed&quot;:&quot;0.002&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"palau congresos\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/07\/palau-congresos.jpg?fit=750%2C465&amp;ssl=1\" class=\"aligncenter  wp-image-4035\" title=\"palau congresos\" src=\"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/07\/palau-congresos.jpg?resize=411%2C254\" alt=\"\" width=\"411\" height=\"254\" srcset=\"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/07\/palau-congresos.jpg?w=750&amp;ssl=1 750w, https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/07\/palau-congresos.jpg?resize=300%2C186&amp;ssl=1 300w\" sizes=\"auto, (max-width: 411px) 100vw, 411px\" \/><\/p>\n<p>Las <strong>obras de construcci\u00f3n del Palacio de Congresos de Palma quedar\u00e1 paralizada<\/strong> al no existir ninguna oferta que cumpla las bases para su explotaci\u00f3n, conforme al concurso p\u00fablico convocado por Cort y el Govern.<\/p>\n<p>Como preocupaci\u00f3n por el estancamiento de las obras, los dos organismos acordar\u00e1n con la empresa constructora una <strong>medida para cerrar las instalaciones<\/strong> y evitar un edificio fantasma.<\/p>\n<p><!--more--><\/p>\n<p>Estas obras estarna detenidas hasta que mejoren las circunstancias econ\u00f3micas y se pueda realizar un nuevo concurso de explotaci\u00f3n y el acabado completo de las edificaciones. La <strong>decisi\u00f3n de paralizar las obras evita que se asuman unos 32 millones de euros<\/strong> correspondientes a los trabajos que quedan aun por ejecutarse. Y tal como manifest\u00f3 Gij\u00f3n, asumir m\u00e1s deuda ser\u00eda irresponsable sin un horizonte de negocio.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las obras de construcci\u00f3n del Palacio de Congresos de Palma quedar\u00e1 paralizada al no existir ninguna oferta que cumpla las[&#8230;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[3021,309,2781,142,1091,3023,1484,2033,3020,5601,3022],"class_list":["post-4034","post","type-post","status-publish","format-standard","hentry","category-eventos-noticias","tag-construccion","tag-cort","tag-edificio","tag-fantasma","tag-govern","tag-instalaciones","tag-negocios","tag-obras","tag-palau-de-congresos","tag-palma","tag-parado"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p1SDLj-134","jetpack-related-posts":[{"id":4752,"url":"https:\/\/www.palmacentro.com\/blog\/se-arreglara-la-zona-apuntalada-de-av-joan-miro-despues-de-2-anos\/","url_meta":{"origin":4034,"position":0},"title":"Se arreglar\u00e1 la zona apuntalada de Av.Joan Mir\u00f3 despu\u00e9s de 2 a\u00f1os","author":"Ver\u00f3nica","date":"07\/09\/2012","format":false,"excerpt":"El Ayuntamiento ha anunciado que iniciar\u00e1 las obras este lunes, para rehabilitar la acera y la calzada del tramo de la Avenida Joan Mir\u00f3, cerca del Palacio de Marivent que fue vallada a causa del derrumbe del muro de un edificio. El hecho que el muro se hubiera ca\u00eddo, provoc\u00f3\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/09\/Av-Joan-Mir%C3%B3.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":4757,"url":"https:\/\/www.palmacentro.com\/blog\/desvios-por-las-obras-de-la-via-cintura\/","url_meta":{"origin":4034,"position":1},"title":"Desvios por las obras de la V\u00eda Cintura","author":"Ver\u00f3nica","date":"07\/09\/2012","format":false,"excerpt":"El inicio de las obras del enlace de la v\u00eda de circunvalaci\u00f3n con la carretera de Manacor (Ma-15), que han provocado el desvi\u00f3 del tr\u00e1fico de un tramo de la V\u00eda de Cintura (Ma-20) de Palma, no ha generado ning\u00fan tipo de retenci\u00f3n en sus primeras horas de funcionamiento. Este\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/09\/carretera-en-obras.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":4110,"url":"https:\/\/www.palmacentro.com\/blog\/se-concede-la-licencia-para-el-macrocentro-comercial-del-coll-den-rebassa\/","url_meta":{"origin":4034,"position":2},"title":"Se concede la licencia para el macrocentro comercial del Coll d&#8217;en Rebassa","author":"Ver\u00f3nica","date":"25\/07\/2012","format":false,"excerpt":"El Govern concedi\u00f3 ayer la licencia para construir un gran centro comercial en el Coll d'en Rebassa, de Carrefour Property, junto al hipermercado existente. Seg\u00fan el comunicado que realizo Carrefour, en los pr\u00f3ximos meses se tramitar\u00e1 la licencia urban\u00edstica ante el Ajuntament de Palma e iniciar con car\u00e1cter inmediato la\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/07\/palma-coll-1024x256.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/07\/palma-coll-1024x256.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/07\/palma-coll-1024x256.jpg?resize=525%2C300 1.5x"},"classes":[]},{"id":4520,"url":"https:\/\/www.palmacentro.com\/blog\/exposicion-homenaje-al-artista-josep-coll-bardolet\/","url_meta":{"origin":4034,"position":3},"title":"Exposici\u00f3n homenaje al artista Josep Coll Bardolet","author":"Ver\u00f3nica","date":"27\/08\/2012","format":false,"excerpt":"El Hotel Barcel\u00f3 Formentor acoge una exposici\u00f3n homenaje al artista Josep Coll Bardolet, organizada por la Consejer\u00eda de Educaci\u00f3n, Cultura y Universidades y la Fundaci\u00f3n Cultural Coll Bardolet. Con esta muestra se pretende hacer un homenaje a Coll Bardolet, con motivo de la celebraci\u00f3n del centenario del nacimiento del artista\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/08\/webcollbardolet.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/08\/webcollbardolet.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/08\/webcollbardolet.jpg?resize=525%2C300 1.5x"},"classes":[]},{"id":7095,"url":"https:\/\/www.palmacentro.com\/blog\/cort-consigue-9-842-e-de-beneficios-en-la-cuenta-de-resultados-de-la-smap\/","url_meta":{"origin":4034,"position":4},"title":"Cort consigue 9.842 \u20ac de beneficios en la cuenta de resultados de la SMAP","author":"Ver\u00f3nica","date":"03\/05\/2013","format":false,"excerpt":"La Sociedad Municipal de Aparcamientos y Proyectos (SMAP) ha presentado las cuentas anuales del 2012, de las que se han obtenido unos beneficios de 9.842 \u20ac, resultado de los ingresos menos los gastos, frente al a\u00f1o anterior que obtuvo unas p\u00e9rdidas de 367.624 \u20ac. Este balance positivo ha sido, seg\u00fan\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"beneficios","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2013\/05\/beneficios1.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":3161,"url":"https:\/\/www.palmacentro.com\/blog\/xxx-fira-del-llibre-23a-setmana-del-llibre-en-catala\/","url_meta":{"origin":4034,"position":5},"title":"XXX Fira del LLibre &#8211; 23\u00aa Setmana del Llibre en Catal\u00e0","author":"Ver\u00f3nica","date":"01\/06\/2012","format":false,"excerpt":"La XXX Fira del LLibre y la 23\u00aa Setmana del Llibre en Catal\u00e0\u00a0 este a\u00f1o se celebrar\u00e1n conjuntamente entre los d\u00edas 1 y 10 de junio en el Parc de ses Estacions. En la presentaci\u00f3n del evento\u00a0 han asistido el director general de Comercio del Govern. C\u00e9sar Pacheco, el vicepresidente\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/05\/fira.jpg?resize=350%2C200","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/posts\/4034","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/comments?post=4034"}],"version-history":[{"count":2,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/posts\/4034\/revisions"}],"predecessor-version":[{"id":4037,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/posts\/4034\/revisions\/4037"}],"wp:attachment":[{"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/media?parent=4034"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/categories?post=4034"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/tags?post=4034"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}