{"id":4153,"date":"2012-07-27T13:18:25","date_gmt":"2012-07-27T11:18:25","guid":{"rendered":"http:\/\/www.palmacentro.com\/blog\/?p=4153"},"modified":"2012-07-27T13:21:37","modified_gmt":"2012-07-27T11:21:37","slug":"los-medicos-por-fin-cobraran-los-pluses","status":"publish","type":"post","link":"https:\/\/www.palmacentro.com\/blog\/los-medicos-por-fin-cobraran-los-pluses\/","title":{"rendered":"Los m\u00e9dicos por fin cobrar\u00e1n los pluses"},"content":{"rendered":"\n<!-- Speed Sense for AdSense WordPress Plugin: https:\/\/wordpress.org\/plugins\/speed-sense\/ -->\n<div id=\"ssp0\" style=\"float:none;margin:10px 0 10px 0;text-align:center;max-width:728px;width:100%;\">\n<ins class=\"adsbygoogle\" id=\"adsgoogle0\" style=\"display: inline-block; width: 100%; height: 90px\"  data-ad-client=\"ca-pub-8118652243852059\" data-ad-slot=\"7814439714\"><\/ins><script>(adsbygoogle = window.adsbygoogle || []).push({});<\/script>\n<\/div>\n<p><a href=\"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/07\/pagando-dinero2.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"4154\" data-permalink=\"https:\/\/www.palmacentro.com\/blog\/los-medicos-por-fin-cobraran-los-pluses\/pagando-dinero2\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/07\/pagando-dinero2.jpg?fit=400%2C300&amp;ssl=1\" data-orig-size=\"400,300\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"pagando-dinero2\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/07\/pagando-dinero2.jpg?fit=400%2C300&amp;ssl=1\" class=\"aligncenter  wp-image-4154\" title=\"pagando-dinero2\" src=\"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/07\/pagando-dinero2.jpg?resize=278%2C208\" alt=\"\" width=\"278\" height=\"208\" srcset=\"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/07\/pagando-dinero2.jpg?w=400&amp;ssl=1 400w, https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/07\/pagando-dinero2.jpg?resize=300%2C225&amp;ssl=1 300w\" sizes=\"auto, (max-width: 278px) 100vw, 278px\" \/><\/a><\/p>\n<p>Ha llegado el<strong> fin de la guerra m\u00e9dica<\/strong> gracias al pacto entre el PP y el PSOE.<br \/>\nLos m\u00e9dicos podr\u00e1n cobrar en la n\u00f3mina de agosto el sueldo correspondiente a ese mes m\u00e1s <strong>todos los atrasos de los pluses<\/strong> que no han cobrado desde la n\u00f3mina de junio. A partir de la aprobaci\u00f3n de la ley, que ser\u00e1 el martes en el Parlament, se abre un periodo para que se convoque a la Mesa Sectorial de Sanidad y se ratifique el cobro definitivo de esos complementos en las siguientes n\u00f3minas.<\/p>\n<p><sub>Via \/ <a href=\"http:\/\/ultimahora.es\/mallorca\/noticia\/noticias\/local\/psib-pactan-extremis-restablecer-complementos-medicos.html\">Ultimahora<\/a><\/sub><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ha llegado el fin de la guerra m\u00e9dica gracias al pacto entre el PP y el PSOE. Los m\u00e9dicos podr\u00e1n[&#8230;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[3155,169,37,1379,3156,2864,3154,1168],"class_list":["post-4153","post","type-post","status-publish","format-standard","hentry","category-eventos-noticias","tag-atrasos","tag-baleares","tag-mallorca","tag-medicos","tag-pacto","tag-paga","tag-pluses","tag-sanidad"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p1SDLj-14Z","jetpack-related-posts":[{"id":2693,"url":"https:\/\/www.palmacentro.com\/blog\/protestas-por-los-recortes-en-los-centros-medicos\/","url_meta":{"origin":4153,"position":0},"title":"Protestas por los recortes en los centros m\u00e9dicos","author":"Ver\u00f3nica","date":"10\/05\/2012","format":false,"excerpt":"Los profesionales sanitarios de Mallorca se han unido hoy en los distintos centros para protestar por los recortes en el sector. La principal reivindicaci\u00f3n es para que el Govern no privatice la sanidad y no cierre el Hospital General y el Hospital de Joan March. En Joan March, los trabajadores\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/05\/2012-05-10_IMG_2012-05-10_10-02-08_sonespases.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":3831,"url":"https:\/\/www.palmacentro.com\/blog\/desconvocan-la-huelga-en-la-sanidad-balear\/","url_meta":{"origin":4153,"position":1},"title":"Desconvocan la huelga en la Sanidad Balear","author":"Ver\u00f3nica","date":"06\/07\/2012","format":false,"excerpt":"El Sindicato M\u00e9dico de Baleares ha desconvocado la huelga indefinida de m\u00e9dicos que dar\u00eda comienzo hoy viernes en Baleares debido a\u00a0 que el Govern Balear se ha comprometido a aprobar una ley en el Parlament para que contin\u00faen cobrando los complementos que reciben desde el a\u00f1o 2008. El presidente del\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/07\/medico21.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":2365,"url":"https:\/\/www.palmacentro.com\/blog\/los-morancos-risoterapia\/","url_meta":{"origin":4153,"position":2},"title":"Los Morancos \u00abRisoterapia\u00bb","author":"Ver\u00f3nica","date":"02\/05\/2012","format":false,"excerpt":"El 12 de mayo veremos actuar a Los Moranco en el Trui Teatre presentando Risoterapia. El espect\u00e1culo empezar\u00e1 a las 21:30h y su precio es desde 30\u20ac. Los protagonistas son dos m\u00e9dicos, uno de la Seguridad Social que las cosas no le van muy bien, y el otro, interpretado por\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/04\/banner-risoterapia.jpeg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":3414,"url":"https:\/\/www.palmacentro.com\/blog\/los-medicos-de-son-llatzer-apoyan-de-forma-unanime-la-huelga-indefinida\/","url_meta":{"origin":4153,"position":3},"title":"Los m\u00e9dicos de Son Ll\u00e0tzer apoyan de forma un\u00e1nime la huelga indefinida","author":"Ver\u00f3nica","date":"12\/06\/2012","format":false,"excerpt":"Los m\u00e9dicos del Hospital Son Ll\u00e0tzer de Palma apoyan de forma un\u00e1nime la convocatoria por parte del Sindicato M\u00e9dico de una huelga indefinida a partir de julio, en caso de que el Govern no rectifique su pretensi\u00f3n de aplicar una sentenciadel Tribunal Superior de Justicia de Baleares, que anula la\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/06\/son-llatzer.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":6000,"url":"https:\/\/www.palmacentro.com\/blog\/los-medicos-agredidos-el-pasado-miercoles-presenan-denuncia\/","url_meta":{"origin":4153,"position":4},"title":"Los m\u00e9dicos agredidos el pasado mi\u00e9rcoles presenan denuncia","author":"Ver\u00f3nica","date":"07\/12\/2012","format":false,"excerpt":"Los tres m\u00e9dicos y la enfermera de Son Espases agredidos el pasado mi\u00e9rcoles mientras trabajaba, han decidido presentar denuncia ante lo que consideran un aut\u00e9ntico linchamiento. El pasado mi\u00e9rcoles, el servicio de Cardiolog\u00eda de Son Espases fue escenario de una m\u00faltiple agresi\u00f3n que iniciaron los familiares de una paciente que\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/12\/agresion-medico.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":4891,"url":"https:\/\/www.palmacentro.com\/blog\/mas-de-326-000-consultas-perdidas-en-2012-porque-los-pacientes-no-se-han-presentado\/","url_meta":{"origin":4153,"position":5},"title":"M\u00e1s de 326.000 consultas perdidas en 2012 porque los pacientes no se han presentado","author":"Ver\u00f3nica","date":"17\/09\/2012","format":false,"excerpt":"Los m\u00e9dicos y enfermeras de la red sanitaria p\u00fablica balear han dejado de atender durante el periodo de enero a agosto de 2012 a 326.869 pacientes de Atenci\u00f3n Primaria y Especializada porque los pacientes no han acudido a la cita que ten\u00edan programada. La cifra, similar a la que se\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/09\/espera-en-consultas.jpg?resize=350%2C200","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/posts\/4153","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/comments?post=4153"}],"version-history":[{"count":2,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/posts\/4153\/revisions"}],"predecessor-version":[{"id":4157,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/posts\/4153\/revisions\/4157"}],"wp:attachment":[{"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/media?parent=4153"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/categories?post=4153"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/tags?post=4153"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}