{"id":4671,"date":"2012-09-17T12:03:42","date_gmt":"2012-09-17T10:03:42","guid":{"rendered":"http:\/\/www.palmacentro.com\/blog\/?p=4671"},"modified":"2012-09-17T14:20:50","modified_gmt":"2012-09-17T12:20:50","slug":"21-septiembre-dia-internacional-de-la-paz","status":"publish","type":"post","link":"https:\/\/www.palmacentro.com\/blog\/21-septiembre-dia-internacional-de-la-paz\/","title":{"rendered":"21 Septiembre &#8211; D\u00eda Internacional de la Paz"},"content":{"rendered":"\n<!-- Speed Sense for AdSense WordPress Plugin: https:\/\/wordpress.org\/plugins\/speed-sense\/ -->\n<div id=\"ssp0\" style=\"float:none;margin:10px 0 10px 0;text-align:center;max-width:728px;width:100%;\">\n<ins class=\"adsbygoogle\" id=\"adsgoogle0\" style=\"display: inline-block; width: 100%; height: 90px\"  data-ad-client=\"ca-pub-8118652243852059\" data-ad-slot=\"7814439714\"><\/ins><script>(adsbygoogle = window.adsbygoogle || []).push({});<\/script>\n<\/div>\n<p><a href=\"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/09\/peaceday_banner.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"4672\" data-permalink=\"https:\/\/www.palmacentro.com\/blog\/21-septiembre-dia-internacional-de-la-paz\/peaceday_banner\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/09\/peaceday_banner.jpg?fit=940%2C165&amp;ssl=1\" data-orig-size=\"940,165\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"peaceday_banner\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/09\/peaceday_banner.jpg?fit=840%2C147&amp;ssl=1\" class=\"aligncenter  wp-image-4672\" title=\"peaceday_banner\" src=\"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/09\/peaceday_banner.jpg?resize=451%2C79\" alt=\"\" width=\"451\" height=\"79\" srcset=\"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/09\/peaceday_banner.jpg?w=940&amp;ssl=1 940w, https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/09\/peaceday_banner.jpg?resize=300%2C52&amp;ssl=1 300w\" sizes=\"auto, (max-width: 451px) 100vw, 451px\" \/><\/a><\/p>\n<p>El <strong>21 de Septiembre<\/strong> se celebra en todo el mundo el <strong>\u201cD\u00eda Internacional de la Paz\u201d<\/strong>, el cual fue declarado en 2001 por la Asamblea General de las Naciones Unidas para <strong>conmemorar y fortalecer los ideales de paz en cada naci\u00f3n y cada pueblo.<\/strong><\/p>\n<p>La Asamblea General declar\u00f3 que ese d\u00eda se observar\u00eda la <strong>cesaci\u00f3n del fuego y la no-violencia a nivel mundial<\/strong>, e invit\u00f3 a todos los Estados Miembros, a las organizaciones del sistema de las Naciones Unidas, a las organizaciones regionales y no gubernamentales y a los particulares a celebrar el D\u00eda, realizando, entre otras cosas, actividades educativas y de sensibilizaci\u00f3n de la opini\u00f3n p\u00fablica.<\/p>\n<p><!--more--><\/p>\n<p>El aumento de la violencia y los conflictos en diversas partes del mundo hacen de gran importancia <strong>la reflexi\u00f3n y la acci\u00f3n para construir y fortalecer una cultura de paz en la sociedad.<\/strong> Si queremos construir el futuro debemos actuar de inmediato y de com\u00fan acuerdo, para que la paz y la no-violencia sean una realidad para todos los seres humanos. <strong><\/strong><\/p>\n<p><sub>Via \/<a href=\"http:\/\/www.un.org\/es\/events\/peaceday\/\">ONU<\/a><\/sub><strong><br \/>\n<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El 21 de Septiembre se celebra en todo el mundo el \u201cD\u00eda Internacional de la Paz\u201d, el cual fue declarado[&#8230;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[3744,734,3738,3743,3740,3742,3739,1453,2533,3741],"class_list":["post-4671","post","type-post","status-publish","format-standard","hentry","category-eventos-noticias","tag-conmemorar","tag-cultura","tag-dia","tag-mundial","tag-naciones-unidas","tag-no-violencia","tag-paz","tag-reflexion","tag-septiembre","tag-sociedad"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p1SDLj-1dl","jetpack-related-posts":[{"id":2786,"url":"https:\/\/www.palmacentro.com\/blog\/17-de-mayo-dia-de-internet-2012\/","url_meta":{"origin":4671,"position":0},"title":"17 de Mayo &#8211; D\u00eda de Internet 2012","author":"Ver\u00f3nica","date":"16\/05\/2012","format":false,"excerpt":"Las Naciones Unidas, a instancias de la II Cumbre Mundial de la Sociedad de la Informaci\u00f3n celebrada en T\u00fanez, aprobaron designar el 17 de Mayo como D\u00eda Mundial de las Telecomunicaciones y de la Sociedad de la Informaci\u00f3n, compartiendo id\u00e9nticos objetivos a los del D\u00eda de Internet. El d\u00eda de\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/05\/gif_banner_DDI_300x250.gif?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":6606,"url":"https:\/\/www.palmacentro.com\/blog\/xv-edicion-de-los-premios-de-internet-2013\/","url_meta":{"origin":4671,"position":1},"title":"XV Edici\u00f3n de los Premios de Internet 2013","author":"Ver\u00f3nica","date":"13\/02\/2013","format":false,"excerpt":"Los Premios de Internet que se convocan anualmente desde 1997 por la Asociaci\u00f3n de Usuarios de Internet, tienen por objetivo reconocer aquellas Iniciativas, Personas u Organizaciones que m\u00e1s se han destacado, durante el a\u00f1o previo a su entrega, en el buen uso de Internet y las nuevas Tecnolog\u00edas en su\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"galardon premios internet","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2013\/02\/galardon-premios-internet.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":5241,"url":"https:\/\/www.palmacentro.com\/blog\/celebracion-dia-de-la-hispanidad-en-palma\/","url_meta":{"origin":4671,"position":2},"title":"Celebraci\u00f3n Dia de la Hispanidad en Palma","author":"Ver\u00f3nica","date":"11\/10\/2012","format":false,"excerpt":"Las pistas deportivas al aire libre y el parking exterior de Son Moix acoger\u00e1n ma\u00f1ana d\u00eda 12 de octubre de 2012, durante todo el d\u00eda los actos l\u00fadicos, deportivos y festivos para conmemorar el D\u00eda de La Hispanidad. En este proyecto han participado el \u00e1rea de Bienestar Social, Inmigraci\u00f3n y\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/10\/Dia-Hispanidad.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":4687,"url":"https:\/\/www.palmacentro.com\/blog\/charla-gratuita-con-motivo-del-dia-mundial-del-alzheimer\/","url_meta":{"origin":4671,"position":3},"title":"Charla gratuita con motivo del d\u00eda mundial del Alzheimer","author":"Ver\u00f3nica","date":"08\/09\/2012","format":false,"excerpt":"Con motivo del d\u00eda mundial del Alzheimer que se celebra el 21 de Septiembre, Cruz Roja dedica especial atenci\u00f3n a las personas afectadas por esta enfermedad y sus cuidadores, ofreciendo charlas gratuitas que les acerque mayor informaci\u00f3n y conocimiento sobre recursos disponibles. El d\u00eda 18 de septiembre habr\u00e1 una charla\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":71,"url":"https:\/\/www.palmacentro.com\/blog\/los-ochenta-son-nuestros\/","url_meta":{"origin":4671,"position":4},"title":"LOS OCHENTA SON NUESTROS","author":"Ver\u00f3nica","date":"26\/09\/2011","format":false,"excerpt":"Una noche de fin de a\u00f1o... y un crimen. Un grupo de amigos que viven una \u00e9poca de constantes cambios sociales y culturales.El amor y la muerte, la sexualidad, la violencia, la amistad, la consciencia o la inconsciencia pol\u00edtica. Una obra que nos demuestra como la juventud es el momento\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2011\/09\/los-ochenta-son-nuestros.jpeg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2011\/09\/los-ochenta-son-nuestros.jpeg?resize=350%2C200 1x, https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2011\/09\/los-ochenta-son-nuestros.jpeg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2011\/09\/los-ochenta-son-nuestros.jpeg?resize=700%2C400 2x"},"classes":[]},{"id":2790,"url":"https:\/\/www.palmacentro.com\/blog\/dia-internacional-de-los-museos-18-de-mayo\/","url_meta":{"origin":4671,"position":5},"title":"Dia Internacional de los Museos -18 de Mayo","author":"Ver\u00f3nica","date":"17\/05\/2012","format":false,"excerpt":"Las entidades que participan par el d\u00eda Internacional de los Museos en Mallorca van desde el Museo sa Bassa Blanca a la Fundaci\u00f3n Yannik y Ben Jakober, el Museo de Art\u00e0, la Casa Museo Lloren\u00e7 Villalonga, el Museo de Historia de Manacor, el Arqueol\u00f3gico de Son Forn\u00e9s, Can Alcover Espacio\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/05\/CARTEL-DIA-INTERNACIONAL-DOS-MUSEOS-300x295.jpg?resize=350%2C200","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/posts\/4671","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/comments?post=4671"}],"version-history":[{"count":7,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/posts\/4671\/revisions"}],"predecessor-version":[{"id":4922,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/posts\/4671\/revisions\/4922"}],"wp:attachment":[{"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/media?parent=4671"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/categories?post=4671"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/tags?post=4671"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}