{"id":5005,"date":"2012-09-24T13:12:12","date_gmt":"2012-09-24T11:12:12","guid":{"rendered":"http:\/\/www.palmacentro.com\/blog\/?p=5005"},"modified":"2012-09-24T13:12:12","modified_gmt":"2012-09-24T11:12:12","slug":"the-dream-syndicate-los-malditos","status":"publish","type":"post","link":"https:\/\/www.palmacentro.com\/blog\/the-dream-syndicate-los-malditos\/","title":{"rendered":"THE DREAM SYNDICATE + Los Malditos"},"content":{"rendered":"\n<!-- Speed Sense for AdSense WordPress Plugin: https:\/\/wordpress.org\/plugins\/speed-sense\/ -->\n<div id=\"ssp0\" style=\"float:none;margin:10px 0 10px 0;text-align:center;max-width:728px;width:100%;\">\n<ins class=\"adsbygoogle\" id=\"adsgoogle0\" style=\"display: inline-block; width: 100%; height: 90px\"  data-ad-client=\"ca-pub-8118652243852059\" data-ad-slot=\"7814439714\"><\/ins><script>(adsbygoogle = window.adsbygoogle || []).push({});<\/script>\n<\/div>\n<p><a href=\"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/09\/the-dream-syndicate.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"5006\" data-permalink=\"https:\/\/www.palmacentro.com\/blog\/the-dream-syndicate-los-malditos\/the-dream-syndicate\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/09\/the-dream-syndicate.jpg?fit=687%2C299&amp;ssl=1\" data-orig-size=\"687,299\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"the-dream-syndicate\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/09\/the-dream-syndicate.jpg?fit=687%2C299&amp;ssl=1\" class=\"aligncenter  wp-image-5006\" title=\"the-dream-syndicate\" src=\"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/09\/the-dream-syndicate.jpg?resize=557%2C242\" alt=\"\" width=\"557\" height=\"242\" srcset=\"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/09\/the-dream-syndicate.jpg?w=687&amp;ssl=1 687w, https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/09\/the-dream-syndicate.jpg?resize=300%2C130&amp;ssl=1 300w\" sizes=\"auto, (max-width: 557px) 100vw, 557px\" \/><\/a><\/p>\n<p>Una de las bandas cl\u00e1sicas del los 80 vendr\u00e1n al <strong>Teatro de Lloseta<\/strong> el d\u00eda <strong>27 de septiembre a las 21h.<\/strong><\/p>\n<p>Nacieron en Los Angeles con la era del Punk, con frecuencia se les considera la quinta esencia del movimiento \u2018paisley underground\u2019.\u00a0The Dream Syndicate combinan la experimentaci\u00f3n s\u00f3nica de la Velvet Underground y el rock aventurero del Dylan de mediados de los \u201960, con la urgencia y la crudeza del punk rock.<\/p>\n<p><!--more--><br \/>\nCon el lanzamiento del \u00e1lbum The Days Of Wine and Roses, se colocaron en la cima, a los ojos de la cr\u00edtica, y todav\u00eda hoy es considerado un disco cl\u00e1sico, no solo en los c\u00edrculos de admiradores de Steve Wynn. Lo rememoran en Lloseta junto al rock de Los Malditos.<\/p>\n<p>Entrada<a href=\"http:\/\/www.fonart.com\/entradas\/\"> anticipada<\/a> 20\u20ac\u00a0 y en taquilla 25\u20ac.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una de las bandas cl\u00e1sicas del los 80 vendr\u00e1n al Teatro de Lloseta el d\u00eda 27 de septiembre a las[&#8230;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[3810,51,3811,239,3813,3808,2709,18,3812,3809],"class_list":["post-5005","post","type-post","status-publish","format-standard","hentry","category-eventos-noticias","tag-bandas","tag-concierto","tag-dream-syndicate","tag-lloseta","tag-los-malditos","tag-punk","tag-rock","tag-teatro","tag-the-days-of-wine-and-roses","tag-underground"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p1SDLj-1iJ","jetpack-related-posts":[{"id":3639,"url":"https:\/\/www.palmacentro.com\/blog\/loquillo-en-lloseta-el-13-de-julio\/","url_meta":{"origin":5005,"position":0},"title":"Loquillo en Lloseta el 13 de julio","author":"Ver\u00f3nica","date":"27\/06\/2012","format":false,"excerpt":"Loquillo en concierto! Podreis disfrutar de Loquillo en els Jardins del Palau d\u2019Aiamans de Lloseta, el viernes 13 de julio a las 21:00h. La necesidad de canalizar en un escenario toda la energ\u00eda que se est\u00e1 generando en el estudio, nos obliga a salir a la carretera. Ya podemos confirmar\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/06\/loquillo-lloseta-2012-230x230.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":6364,"url":"https:\/\/www.palmacentro.com\/blog\/baile-de-carnaval-gratuito-y-con-premios-en-lloseta\/","url_meta":{"origin":5005,"position":1},"title":"Baile de Carnaval gratuito y con premios en Lloseta","author":"Ver\u00f3nica","date":"28\/01\/2013","format":false,"excerpt":"BAILE DE CARNAVAL el d\u00eda 9 de febrero en el Teatro de Lloseta a partir de las 23h, entrada gratuita. Todas las personas que quieran participar al concurso de disfraces deben inscribirse antes de las 00:45h en la recepci\u00f3n del teatro. El desfile de participantes sera a partir de la\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"ball carnaval lloseta","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2013\/01\/ball-carnaval-lloseta-300x137.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":1790,"url":"https:\/\/www.palmacentro.com\/blog\/vinamica-showroom-2012\/","url_meta":{"origin":5005,"position":2},"title":"Vinamica Showroom 2012","author":"Ver\u00f3nica","date":"14\/03\/2012","format":false,"excerpt":"Mi\u00e9rcoles d\u00eda 14 de Marzo en el Teatre de Lloseta, de las 16:00h. hasta las 21:30h se celebra nueva edici\u00f3n de Vinamica Showroom 2012. Durante el evento tendr\u00e9is la oportunidad de catar las propuestas vin\u00edcolas m\u00e1s interesantes de la Pen\u00ednsula y algunos de los mejores vinos de Mallorca, dichos vinos\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/03\/vinamica-showroom-2011-teatre-lloseta.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":5580,"url":"https:\/\/www.palmacentro.com\/blog\/impresentables-en-conierto\/","url_meta":{"origin":5005,"position":3},"title":"Impresentables en conierto","author":"Ver\u00f3nica","date":"31\/10\/2012","format":false,"excerpt":"Una de las bandas m\u00e1s en forma de la escena punk rock local, Los Impresentables dar\u00e1n un concierto el d\u00eda 2 de noviembre en la Factoria del So a las 22h. Con su rock castizo en castellano en la linea de Rosendo, Extremoduro, Le\u00f1o, Asfalto... siempre con un toque muy\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/10\/concierto-300x198.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":6361,"url":"https:\/\/www.palmacentro.com\/blog\/la-gran-orquesta-republicana-en-concierto-el-23-de-febero\/","url_meta":{"origin":5005,"position":4},"title":"La Gran Orquesta Republicana en concierto el 23 de febrero","author":"Ver\u00f3nica","date":"05\/02\/2013","format":false,"excerpt":"El d\u00eda 23 de febrero a las 21:30h, La Gran Orquesta Republicana dar\u00e1 un concierto en el Teatro de Lloseta. En esta gira la banda se presenta en formato reducido. Dar\u00e1n un repaso a su discograf\u00eda y estrenar\u00e1n algunas las nuevas canciones que formaran parte de su nuevo disco \"Capitalismo\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"la gran orquesta republicana","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2013\/01\/la-gran-orquesta-republicana-300x170.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":534,"url":"https:\/\/www.palmacentro.com\/blog\/aba-taano\/","url_meta":{"origin":5005,"position":5},"title":"ABA TAANO","author":"Ver\u00f3nica","date":"30\/11\/2011","format":false,"excerpt":"Aba Taano, significa \"los cinco\" a Luganda a dem\u00e1s de ser el nombre de los cantantes del pr\u00f3ximo concierto en Sa Pobla el dia 7 de diciembre a las 19:00h. La entrada es de 10 \u20ac y ser\u00e1 en Sa Congregaci\u00f3 \u00b7 Espai Jove c\/Rosari, 25 de Sa Pobla. 6\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2011\/11\/aba-taano.jpg?resize=350%2C200","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/posts\/5005","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/comments?post=5005"}],"version-history":[{"count":2,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/posts\/5005\/revisions"}],"predecessor-version":[{"id":5008,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/posts\/5005\/revisions\/5008"}],"wp:attachment":[{"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/media?parent=5005"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/categories?post=5005"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/tags?post=5005"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}