{"id":5046,"date":"2012-10-03T12:11:33","date_gmt":"2012-10-03T10:11:33","guid":{"rendered":"http:\/\/www.palmacentro.com\/blog\/?p=5046"},"modified":"2012-10-03T12:11:33","modified_gmt":"2012-10-03T10:11:33","slug":"tito-davila-en-concierto-el-12-de-octubre","status":"publish","type":"post","link":"https:\/\/www.palmacentro.com\/blog\/tito-davila-en-concierto-el-12-de-octubre\/","title":{"rendered":"Tito Davila en concierto el 12 de octubre"},"content":{"rendered":"\n<!-- Speed Sense for AdSense WordPress Plugin: https:\/\/wordpress.org\/plugins\/speed-sense\/ -->\n<div id=\"ssp0\" style=\"float:none;margin:10px 0 10px 0;text-align:center;max-width:728px;width:100%;\">\n<ins class=\"adsbygoogle\" id=\"adsgoogle0\" style=\"display: inline-block; width: 100%; height: 90px\"  data-ad-client=\"ca-pub-8118652243852059\" data-ad-slot=\"7814439714\"><\/ins><script>(adsbygoogle = window.adsbygoogle || []).push({});<\/script>\n<\/div>\n<p><a href=\"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/09\/tito_davila.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"5047\" data-permalink=\"https:\/\/www.palmacentro.com\/blog\/tito-davila-en-concierto-el-12-de-octubre\/tito_davila\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/09\/tito_davila.jpg?fit=275%2C250&amp;ssl=1\" data-orig-size=\"275,250\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"tito_davila\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/09\/tito_davila.jpg?fit=275%2C250&amp;ssl=1\" class=\"aligncenter size-full wp-image-5047\" title=\"tito_davila\" src=\"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/09\/tito_davila.jpg?resize=275%2C250\" alt=\"\" width=\"275\" height=\"250\" \/><\/a><\/p>\n<p>Tito Davila, uno de los m\u00fasicos imprescindibles del rock espa\u00f1ol adem\u00e1s de teclista y productor, vuelve a La Movida Cafe Concierto el d\u00eda 12 de octubre , junto a su banda de m\u00fasicos mallorquines para interpretar versiones de artistas como : Andres Calamaro, Ariel Rot, Jorge Drexler, Los Ronaldos, Miguel Rios, as\u00ed como tambi\u00e9n temas propios.<\/p>\n<p><sub>V\u00eda \/ <a href=\"http:\/\/lamovida-cafeconcierto.com\/noticias#70\">LaMovidacafe<\/a><\/sub><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tito Davila, uno de los m\u00fasicos imprescindibles del rock espa\u00f1ol adem\u00e1s de teclista y productor, vuelve a La Movida Cafe[&#8230;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[3841,3842,51,3839,3686,3843,5601,3840,3844,3838],"class_list":["post-5046","post","type-post","status-publish","format-standard","hentry","category-eventos-noticias","tag-andres-calamaro","tag-ariel-ror","tag-concierto","tag-grupo","tag-la-movida-cafe","tag-miguel-rios","tag-palma","tag-teclista","tag-temas-propios","tag-tito-davila"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p1SDLj-1jo","jetpack-related-posts":[{"id":6524,"url":"https:\/\/www.palmacentro.com\/blog\/amistades-peligrosas-de-nuevo-en-la-movida-cafe\/","url_meta":{"origin":5046,"position":0},"title":"Amistades Peligrosas de nuevo en La Movida Caf\u00e9","author":"Ver\u00f3nica","date":"06\/02\/2013","format":false,"excerpt":"Amistades Peligrosas de nuevo en La Movida Caf\u00e9 Concierto el viernes 8 de febrero a las 22h para presentarnos sus temas m\u00e1s\u00a0 nuevos. Se presenta como un d\u00fao renovado, actualizado, lleno de frescura, con la riqueza de nuevos sonidos y ampliaci\u00f3n de estilos donde se mezclan el pop, el etno-pop,\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"amistades_peligrosas","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2013\/02\/amistades_peligrosas.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":5052,"url":"https:\/\/www.palmacentro.com\/blog\/en-concierto-el-17-de-noviembre-gatos-locos\/","url_meta":{"origin":5046,"position":1},"title":"En concierto el 17 de noviembre Gatos Locos","author":"Ver\u00f3nica","date":"12\/11\/2012","format":false,"excerpt":"Gatos Locos en concierto el d\u00eda 17 de noviembre en La Movida cafe. Con 25 a\u00f1os de carrera, 11 discos y uno de ellos de oro, canciones como \u201cCorro hacia ti\u201d o \u201cCruce de caminos\u201d que llegaron al n\u00ba1 de las listas, avalan esta banda icono de los a\u00f1os 80-90.\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/09\/gatos-locos.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":5049,"url":"https:\/\/www.palmacentro.com\/blog\/nacha-pop-en-concierto-en-la-movida-cafe\/","url_meta":{"origin":5046,"position":2},"title":"Nacha Pop en concierto en La Movida cafe","author":"Ver\u00f3nica","date":"30\/10\/2012","format":false,"excerpt":"Nacha Pop vuelve a los escenarios sin Antonio Vega el d\u00eda 9 de noviembre\u00a0 en La Movida cafe de Palma. \u201cVolvemos a tocar. Nos lo ped\u00edan los fans. Y en la oficina de contrataci\u00f3n de Nacha Pop, el tel\u00e9fono no ha dejado de sonar en estos \u00faltimos meses\u201d, avanza Nacho\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/09\/nacha_pop.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":4846,"url":"https:\/\/www.palmacentro.com\/blog\/amistades-peligrosas-vueleve-y-lo-hara-en-la-movida\/","url_meta":{"origin":5046,"position":3},"title":"Amistades Peligrosas vueleve y lo har\u00e1 en La Movida","author":"Ver\u00f3nica","date":"12\/09\/2012","format":false,"excerpt":"Con una carrera musical de m\u00e1s de una d\u00e9cada , con m\u00e1s de tres millones de discos vendidos y seis discos editados en el mercado , vuelve Amistades Peligrosas y lo har\u00e1 en La Movida Cafe el 14 de septiembre a las 22:30h. El d\u00fao espa\u00f1ol que marc\u00f3 los noventa\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/09\/Amistades-Peligrosas-.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":6730,"url":"https:\/\/www.palmacentro.com\/blog\/concierto-de-paula-rojo-el-dia-15-de-marzo-en-la-movida-cafe\/","url_meta":{"origin":5046,"position":4},"title":"Concierto de Paula Rojo el d\u00eda 15 de marzo en La Movida caf\u00e9","author":"Ver\u00f3nica","date":"25\/02\/2013","format":false,"excerpt":"PAULA ROJO en concierto el d\u00eda 15 de marzo a las 22:30h en La Movida caf\u00e9. Paula fue una de las cantantes expulsada del programa \u00abLa Voz\u00bb que pertenec\u00eda al grupo de Melendi pero eso no ha sido obst\u00e1culo para que siga adelante . Desde que se public\u00f3 el 18\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"Paula-Rojo","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2013\/02\/Paula-Rojo.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":4452,"url":"https:\/\/www.palmacentro.com\/blog\/28-sep-anglada-simfonic-en-el-trui-teatre\/","url_meta":{"origin":5046,"position":5},"title":"Anglada Simf\u00f2nic en el Trui Teatre","author":"Ver\u00f3nica","date":"23\/09\/2012","format":false,"excerpt":"ANGLADA SIMF\u00d2NIC,es el concierto interpretado por el cantante Jaime Anglada y la Orquestra Simf\u00f2nica de les Illes Balears que tendr\u00e1 lugar el d\u00eda 28 de septiembre a las 21:30h en el Trui Teatre. Un minucioso y elaborado trabajo en los arreglos, permite que la adaptaci\u00f3n de temas con esp\u00edritu rockero\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/08\/anglada-simf%C3%B3nic.jpg?resize=350%2C200","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/posts\/5046","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/comments?post=5046"}],"version-history":[{"count":2,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/posts\/5046\/revisions"}],"predecessor-version":[{"id":5126,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/posts\/5046\/revisions\/5126"}],"wp:attachment":[{"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/media?parent=5046"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/categories?post=5046"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/tags?post=5046"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}