{"id":5231,"date":"2012-10-11T13:36:40","date_gmt":"2012-10-11T11:36:40","guid":{"rendered":"http:\/\/www.palmacentro.com\/blog\/?p=5231"},"modified":"2012-10-11T13:38:28","modified_gmt":"2012-10-11T11:38:28","slug":"la-xi-mostra-de-la-llampuga-en-capdepera","status":"publish","type":"post","link":"https:\/\/www.palmacentro.com\/blog\/la-xi-mostra-de-la-llampuga-en-capdepera\/","title":{"rendered":"La XI Mostra de la Llampuga en Capdepera"},"content":{"rendered":"\n<!-- Speed Sense for AdSense WordPress Plugin: https:\/\/wordpress.org\/plugins\/speed-sense\/ -->\n<div id=\"ssp0\" style=\"float:none;margin:10px 0 10px 0;text-align:center;max-width:728px;width:100%;\">\n<ins class=\"adsbygoogle\" id=\"adsgoogle0\" style=\"display: inline-block; width: 100%; height: 90px\"  data-ad-client=\"ca-pub-8118652243852059\" data-ad-slot=\"7814439714\"><\/ins><script>(adsbygoogle = window.adsbygoogle || []).push({});<\/script>\n<\/div>\n<p><a href=\"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/10\/Cartell-llampuga-2012.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"5232\" data-permalink=\"https:\/\/www.palmacentro.com\/blog\/la-xi-mostra-de-la-llampuga-en-capdepera\/cartell-llampuga-2012\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/10\/Cartell-llampuga-2012.jpg?fit=472%2C668&amp;ssl=1\" data-orig-size=\"472,668\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"Cartell-llampuga-2012\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/10\/Cartell-llampuga-2012.jpg?fit=472%2C668&amp;ssl=1\" class=\"aligncenter  wp-image-5232\" title=\"Cartell-llampuga-2012\" src=\"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/10\/Cartell-llampuga-2012.jpg?resize=388%2C500\" alt=\"\" width=\"388\" height=\"500\" \/><\/a><\/p>\n<p>En su presentaci\u00f3n, el alcalde ha comentado la importancia de esta feria para promocionar la gastronom\u00eda de la zona y para que los turistas disfruten tambi\u00e9n de ella.Adem\u00e1s, ha agradecido la implicaci\u00f3n de todos los colaboradores, de los organizadores y de todos los participantes.<\/p>\n<p>El viernes 12 de octubre podr\u00e9is disfrutar de las Tapes al Moll a partir de las 18h, con entrada gratuita y contar\u00e1 de 5 expositores, as\u00ed como de grupos musicales\u00a0 y se realizar\u00e1 un concurso de tapas.<\/p>\n<p><!--more--><\/p>\n<p>Para el d\u00eda 14 a las 12h la feria abrir\u00e1 sus pertas al p\u00fablico hasta las 22h, con un precio de 4\u20ac y de regalo un vaso de helado. En la feria se pueden comprar tickets de comida por 2\u20ac y bebidas por 1,5 \u20ac.\u00a0 El evento contar\u00e1 con\u00a0 14 expositores y se utilizar\u00e1n 2.200 kilos de llampuga.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En su presentaci\u00f3n, el alcalde ha comentado la importancia de esta feria para promocionar la gastronom\u00eda de la zona y[&#8230;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[3971,1760,51,1455,2354,3972,37,108,3974,3975,45,3973],"class_list":["post-5231","post","type-post","status-publish","format-standard","hentry","category-eventos-noticias","tag-cala-ratjada","tag-capdepera","tag-concierto","tag-entrada","tag-gastronomia","tag-llampuga","tag-mallorca","tag-musica","tag-pescado-fresco","tag-pix-fresc","tag-tapas","tag-tickets"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p1SDLj-1mn","jetpack-related-posts":[{"id":7761,"url":"https:\/\/www.palmacentro.com\/blog\/xii-mostra-de-la-llampuga-en-cala-ratjada-del-11-al-13-de-octubre\/","url_meta":{"origin":5231,"position":0},"title":"XII Mostra de la Llampuga en Cala Ratjada del 11 al 13 de octubre","author":"Ver\u00f3nica","date":"10\/10\/2013","format":false,"excerpt":"\u00a0 Durante los d\u00edas 11, 12 y 13 de octubre de 2013\u00a0 se celebra en Cala Ratjada la XII Fira de la Llampuga. La cofrad\u00eda de pescadores de Cala Rajada cada a\u00f1o organiza por estas fechas la Mostra de la llampuga. Este evento es de \u00e1mbito gastron\u00f3mico donde se presentan\u00a0\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"LLAMPUGA","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2013\/10\/LLAMPUGA.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":7795,"url":"https:\/\/www.palmacentro.com\/blog\/feria-de-la-sobrassada-y-firo-nocturn-en-campos-programa\/","url_meta":{"origin":5231,"position":1},"title":"Feria de la Sobrassada y Fir\u00f3 Nocturn en Campos &#8211; Programa","author":"Ver\u00f3nica","date":"17\/10\/2013","format":false,"excerpt":"Los d\u00edas 17, 18, 19 y 20 de octubre se celebra la Feria de octubre, de la Sobrassada y el Fir\u00f3 Nocturn a Campos. El protagonista de la feria es sin duda la sobrassada, donde durante estos d\u00edas se podr\u00e1 disfrutar de este producto t\u00edpico en los restaurantes y bares,\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"campos feria","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2013\/10\/campos-feria.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2013\/10\/campos-feria.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2013\/10\/campos-feria.jpg?resize=525%2C300 1.5x"},"classes":[]},{"id":4095,"url":"https:\/\/www.palmacentro.com\/blog\/i-feria-solidaria-de-intercambio-de-libros-usados-en-sa-cabaneta\/","url_meta":{"origin":5231,"position":2},"title":"I Feria Solidaria de intercambio de libros usados en Sa Cabaneta","author":"Ver\u00f3nica","date":"25\/07\/2012","format":false,"excerpt":"Los pr\u00f3ximos d\u00edas 27 y 28 de julio se realizar\u00e1 la I Fira Solidaria que ha iniciado la asociaci\u00f3n de vecinos de Sa Cabaneta en es CAMPET. Para la recogida previa de libros a la feria, se contar\u00e1 con la colaboraci\u00f3n de los comercios de Sa Cabaneta, P\u00f2rtol y Es\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/07\/foto_parnot237867.png?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":1807,"url":"https:\/\/www.palmacentro.com\/blog\/feria-de-stocks-con-la-colaboracion-de-palmaactiva\/","url_meta":{"origin":5231,"position":3},"title":"Feria de stocks con la colaboraci\u00f3n de PalmaActiva","author":"Ver\u00f3nica","date":"14\/03\/2012","format":false,"excerpt":"Esperan\u00e7a Cresp\u00ed ha presentado en la Pla\u00e7a Major la nueva edici\u00f3n de la Feria de stocks, que se llevar\u00e1 a cabo los d\u00edas 15, 16 y 17 de marzo. PalmaActiva colabora con esta iniciativa para dar soporte al peque\u00f1o y mediano comercio de Palma. Cresp\u00ed ha declarado que este a\u00f1o\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/03\/Presentaci%C3%B3-Fira-dEstocs-300x225.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":5317,"url":"https:\/\/www.palmacentro.com\/blog\/fira-de-sa-sobrassada-en-campos\/","url_meta":{"origin":5231,"position":4},"title":"Fira de Sa Sobrassada en Campos","author":"Ver\u00f3nica","date":"17\/10\/2012","format":false,"excerpt":"18 octubre Podr\u00e9is disfrutar de las Feria tradicional por las calles de la Vila as\u00ed como de la\u00a0 V Fira de Sa Sobrassada de Mallorca de 10h- 14h y de 16h-19:30h en el Auditorium. SHOWCOOKING con el cocinero Gabriel Perell\u00f3 a las 18h con la elaboraci\u00f3n en directo de\u00a0 CARAMELS\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/10\/v-fira-de-sa-sobrassada-campos-mallorca.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":8926,"url":"https:\/\/www.palmacentro.com\/blog\/ii-feria-de-pina-20-de-septiembre\/","url_meta":{"origin":5231,"position":5},"title":"II FERIA DE PINA &#8211; 20 de Septiembre","author":"PalmaCentro","date":"22\/08\/2017","format":false,"excerpt":"Pina celebra el pr\u00f3ximo S\u00e1bado 20 de Septiembre, la II Feria de Pina a partir de las 17h en el\u00a0patio de las Hermanas Franciscanas. Podr\u00e9is encontrar una muestra de productos artesanales y gastron\u00f3micos de los conventos y monasterios de Mallorca. Tambi\u00e9n se har\u00e1n visitas guiadas a la Iglesia, la rector\u00eda,\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2017\/08\/ii-fira-de-pina.jpg?resize=350%2C200","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/posts\/5231","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/comments?post=5231"}],"version-history":[{"count":3,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/posts\/5231\/revisions"}],"predecessor-version":[{"id":5234,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/posts\/5231\/revisions\/5234"}],"wp:attachment":[{"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/media?parent=5231"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/categories?post=5231"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/tags?post=5231"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}