{"id":5722,"date":"2012-11-12T13:50:20","date_gmt":"2012-11-12T11:50:20","guid":{"rendered":"http:\/\/www.palmacentro.com\/blog\/?p=5722"},"modified":"2012-11-12T13:50:20","modified_gmt":"2012-11-12T11:50:20","slug":"suprimen-la-ora-hasta-el-31-de-marzo-en-el-tramo-de-joan-miro","status":"publish","type":"post","link":"https:\/\/www.palmacentro.com\/blog\/suprimen-la-ora-hasta-el-31-de-marzo-en-el-tramo-de-joan-miro\/","title":{"rendered":"Suprimen la ORA hasta el 31 de marzo en el tramo de Joan Mir\u00f3"},"content":{"rendered":"\n<!-- Speed Sense for AdSense WordPress Plugin: https:\/\/wordpress.org\/plugins\/speed-sense\/ -->\n<div id=\"ssp0\" style=\"float:none;margin:10px 0 10px 0;text-align:center;max-width:728px;width:100%;\">\n<ins class=\"adsbygoogle\" id=\"adsgoogle0\" style=\"display: inline-block; width: 100%; height: 90px\"  data-ad-client=\"ca-pub-8118652243852059\" data-ad-slot=\"7814439714\"><\/ins><script>(adsbygoogle = window.adsbygoogle || []).push({});<\/script>\n<\/div>\n<div>\n<p><a href=\"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/11\/ora.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"5723\" data-permalink=\"https:\/\/www.palmacentro.com\/blog\/suprimen-la-ora-hasta-el-31-de-marzo-en-el-tramo-de-joan-miro\/ora-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/11\/ora.jpg?fit=208%2C276&amp;ssl=1\" data-orig-size=\"208,276\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"ora\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/11\/ora.jpg?fit=208%2C276&amp;ssl=1\" class=\"aligncenter size-full wp-image-5723\" title=\"ora\" src=\"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/11\/ora.jpg?resize=208%2C276\" alt=\"\" width=\"208\" height=\"276\" \/><\/a><\/p>\n<p>El Ayuntamiento de Palma aprob\u00f3 por Decreto dejar <strong>sin<\/strong> efecto la regulaci\u00f3n de estacionamiento mediante<strong> ORA<\/strong>, e<strong>l tramo de la avenida Joan Mir\u00f3<\/strong> comprendidas entre Marivent y el club de vela Calanova, que marca el final del t\u00e9rmino municipal de Palma.<\/p>\n<p>Durante los meses <strong>de noviembre hasta el 31 de marzo<\/strong>\u00a0 la zona de aparcamiento tarifado en este tramo de Joan Mir\u00f3 pasar\u00e1 a ser gratuita. Con esta medida, Cort ha atendido a una petici\u00f3n de la Asociaci\u00f3n de Vecinos de San Agust\u00edn para que modificara el funcionamiento de la ORA en ese lugar tras constatar el bajo \u00edndice de ocupaci\u00f3n de la zona azul en temporada baja.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>El Ayuntamiento de Palma aprob\u00f3 por Decreto dejar sin efecto la regulaci\u00f3n de estacionamiento mediante ORA, el tramo de la[&#8230;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[790,1044,3341,788,3549],"class_list":["post-5722","post","type-post","status-publish","format-standard","hentry","category-eventos-noticias","tag-gratis","tag-joan-miro","tag-marivent","tag-ora","tag-tramo"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p1SDLj-1ui","jetpack-related-posts":[{"id":4752,"url":"https:\/\/www.palmacentro.com\/blog\/se-arreglara-la-zona-apuntalada-de-av-joan-miro-despues-de-2-anos\/","url_meta":{"origin":5722,"position":0},"title":"Se arreglar\u00e1 la zona apuntalada de Av.Joan Mir\u00f3 despu\u00e9s de 2 a\u00f1os","author":"Ver\u00f3nica","date":"07\/09\/2012","format":false,"excerpt":"El Ayuntamiento ha anunciado que iniciar\u00e1 las obras este lunes, para rehabilitar la acera y la calzada del tramo de la Avenida Joan Mir\u00f3, cerca del Palacio de Marivent que fue vallada a causa del derrumbe del muro de un edificio. El hecho que el muro se hubiera ca\u00eddo, provoc\u00f3\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/09\/Av-Joan-Mir%C3%B3.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":1958,"url":"https:\/\/www.palmacentro.com\/blog\/palma-dejara-de-ser-una-ciudad-cerrada-abre-los-domingos\/","url_meta":{"origin":5722,"position":1},"title":"Palma dejar\u00e1 de ser una ciudad cerrada, abre los domingos.","author":"Ver\u00f3nica","date":"26\/03\/2012","format":false,"excerpt":"El presidente del Govern, Jos\u00e9 Ram\u00f3n Bauz\u00e1, y el alcalde de Palma, Mateu Isern, han opinado este lunes en que la apertura en domingos y festivos de los comercios situados entre las Avenidas hasta el Paseo Mallorca y el Mar\u00edtimo conseguir\u00e1 que la Palma \"deje de ser una ciudad cerrada\"\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/03\/tiendas-300x178.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":4003,"url":"https:\/\/www.palmacentro.com\/blog\/concierto-gratuito-de-catende-trio-en-la-fundacio-pilar-i-joan-miro\/","url_meta":{"origin":5722,"position":2},"title":"Concierto gratuito de Catend\u00e9 Trio en la Fundaci\u00f3 Pilar i Joan Mir\u00f3","author":"Ver\u00f3nica","date":"19\/07\/2012","format":false,"excerpt":"En el programa de conciertos de verano de la Fundaci\u00f3 Pilar i Joan Mir\u00f3 tenemos para este viernes 20 de julio al grupo Catend\u00e9 Trio. un grupo que trabaja con un repertorio de canciones de samba, bossanova, m\u00fasica popular brasile\u00f1a y jazz. Un espect\u00e1culo gratuito que empezar\u00e1 a las 22h\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/07\/trio.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":2069,"url":"https:\/\/www.palmacentro.com\/blog\/tres-redadas-en-discotecas-latinas-de-palma\/","url_meta":{"origin":5722,"position":3},"title":"Tres redadas en discotecas latinas de Palma","author":"Ver\u00f3nica","date":"04\/04\/2012","format":false,"excerpt":"\u00a0 La Polic\u00eda Local de Palma llev\u00f3 a cabo en la madrugada del domingo tres registros en locales nocturnos frecuentados por sudamericanos y caribe\u00f1os, en\u00a0 los pol\u00edgonos de Son Castell\u00f3, Can Valero y la calle Joan Mir\u00f3. Las nuevas directrices son de tolerancia cero con las discos ilegales o las\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":6023,"url":"https:\/\/www.palmacentro.com\/blog\/azme-el-humor-concurso-monologos-en-shambhala\/","url_meta":{"origin":5722,"position":4},"title":"Azme el humor &#8211; Concurso mon\u00f3logos en Shambhala","author":"Ver\u00f3nica","date":"11\/12\/2012","format":false,"excerpt":"El Shambhala esta organizando un concurso de monologos!!! Si estais interesados en participar, podeis inscribiros llamando al telefono 971 731 481, o personarse en el local ( Avda. Joan Miro n\u00ba 7). El plazo de inscripcion es hasta el 12 de diciembre. Todos los concursantes tendr\u00e1n premio!!!! Y el ganador\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/12\/concurso-monologos-300x195.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":4010,"url":"https:\/\/www.palmacentro.com\/blog\/obras-de-asfaltado-en-la-calle-aragon\/","url_meta":{"origin":5722,"position":5},"title":"Obras de asfaltado en la calle Arag\u00f3n","author":"Ver\u00f3nica","date":"20\/07\/2012","format":false,"excerpt":"El \u00e1rea de Infraestructuras del Ayuntamiento de Palma realiza trabajos de asfaltado en la calle Arag\u00f3n durante el d\u00eda de hoy, viernes 20 de julio. El trabajo est\u00e1 comprendido en el tramo de la calle Arag\u00f3n desde G\u00fcell hasta la calle Joan Burgu\u00e9s Zaforteza, que se se\u00f1alizar\u00e1 con sentido \u00fanico\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/07\/obras-arag%C3%B3n1.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/07\/obras-arag%C3%B3n1.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/07\/obras-arag%C3%B3n1.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/07\/obras-arag%C3%B3n1.jpg?resize=700%2C400 2x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/posts\/5722","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/comments?post=5722"}],"version-history":[{"count":1,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/posts\/5722\/revisions"}],"predecessor-version":[{"id":5724,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/posts\/5722\/revisions\/5724"}],"wp:attachment":[{"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/media?parent=5722"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/categories?post=5722"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/tags?post=5722"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}