{"id":5997,"date":"2012-12-07T13:38:12","date_gmt":"2012-12-07T11:38:12","guid":{"rendered":"http:\/\/www.palmacentro.com\/blog\/?p=5997"},"modified":"2012-12-07T13:38:12","modified_gmt":"2012-12-07T11:38:12","slug":"se-mantiene-la-huelga-de-iberia-para-los-dias-14171920-y-21-de-diciembre","status":"publish","type":"post","link":"https:\/\/www.palmacentro.com\/blog\/se-mantiene-la-huelga-de-iberia-para-los-dias-14171920-y-21-de-diciembre\/","title":{"rendered":"Se mantiene la huelga de Iberia para los d\u00edas 14,17,19,20 y 21 de diciembre"},"content":{"rendered":"\n<!-- Speed Sense for AdSense WordPress Plugin: https:\/\/wordpress.org\/plugins\/speed-sense\/ -->\n<div id=\"ssp0\" style=\"float:none;margin:10px 0 10px 0;text-align:center;max-width:728px;width:100%;\">\n<ins class=\"adsbygoogle\" id=\"adsgoogle0\" style=\"display: inline-block; width: 100%; height: 90px\"  data-ad-client=\"ca-pub-8118652243852059\" data-ad-slot=\"7814439714\"><\/ins><script>(adsbygoogle = window.adsbygoogle || []).push({});<\/script>\n<\/div>\n<p><a href=\"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/12\/iberia-huelga.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"5998\" data-permalink=\"https:\/\/www.palmacentro.com\/blog\/se-mantiene-la-huelga-de-iberia-para-los-dias-14171920-y-21-de-diciembre\/iberia-huelga-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/12\/iberia-huelga.jpg?fit=480%2C200&amp;ssl=1\" data-orig-size=\"480,200\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"iberia-huelga\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/12\/iberia-huelga.jpg?fit=480%2C200&amp;ssl=1\" class=\"aligncenter  wp-image-5998\" title=\"iberia-huelga\" src=\"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/12\/iberia-huelga.jpg?resize=428%2C178\" alt=\"\" width=\"428\" height=\"178\" srcset=\"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/12\/iberia-huelga.jpg?w=480&amp;ssl=1 480w, https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/12\/iberia-huelga.jpg?resize=300%2C125&amp;ssl=1 300w\" sizes=\"auto, (max-width: 428px) 100vw, 428px\" \/><\/a><\/p>\n<p>Los <strong>sindicatos de Iberia<\/strong> mantienen la <strong>huelga<\/strong> prevista para los d\u00edas <strong>14, 17, 18, 19, 20 y 21 de diciembre<\/strong> al no haber llegado a un acuerdo con la compa\u00f1\u00eda, seg\u00fan fuentes sindicales.<\/p>\n<p>El portavoz de UGT, Manuel Atienza, comentaba que la aerol\u00ednea ha rechazado la propuesta presentada\u00a0 como son la no segregaci\u00f3n de los negocios o que no se levara a cabo el Expediente de Regulaci\u00f3n de Empleo (ERE) propuesto.<!--more--><\/p>\n<p>Los sindicatos representantes de Iberia, pretenden con estas seis jornadas de huelga luchar contra el plan de reestructuraci\u00f3n planteado por la compa\u00f1\u00eda, que implica el <strong>despido de 4.500 trabajadores.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los sindicatos de Iberia mantienen la huelga prevista para los d\u00edas 14, 17, 18, 19, 20 y 21 de diciembre[&#8230;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[28,179,2195,346,511,4505,1846,2216,2675],"class_list":["post-5997","post","type-post","status-publish","format-standard","hentry","category-eventos-noticias","tag-despido","tag-diciembre","tag-ere","tag-huelga","tag-iberia","tag-reunion","tag-sindicatos","tag-trabajadores","tag-vacaciones"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p1SDLj-1yJ","jetpack-related-posts":[{"id":5926,"url":"https:\/\/www.palmacentro.com\/blog\/iberia-ve-inoportuna-la-huelga\/","url_meta":{"origin":5997,"position":0},"title":"Iberia ve inoportuna la huelga","author":"Ver\u00f3nica","date":"29\/11\/2012","format":false,"excerpt":"El consejero delegado de Iberia, Rafael S\u00e1nchez-Lozano, ha considerado que una huelga en la aerol\u00ednea contra el plan de reestructuraci\u00f3n es \"absolutamente inoportuna e irresponsable\" y \"completamente injustificada\", ya que,\u00a0 la compa\u00f1\u00eda est\u00e1 dispuesta a \"discutir alternativas\". \"Ni Espa\u00f1a ni Iberia pueden permitirse esa huelga\", ha indicado en una entrevista\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/11\/iberia-huelga.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":6030,"url":"https:\/\/www.palmacentro.com\/blog\/iberia-desconvoca-la-huelga\/","url_meta":{"origin":5997,"position":1},"title":"Iberia desconvoca la huelga","author":"Ver\u00f3nica","date":"11\/12\/2012","format":false,"excerpt":"La reuni\u00f3n entre la direcci\u00f3n de Iberia y los sindicatos en el Servicio Interconfederal de Mediaci\u00f3n y Arbitraje\u00a0 ha concluido \u201csin ning\u00fan acuerdo\u201d, seg\u00fan inform\u00f3 el portavoz del sector a\u00e9reo de UGT, quien avanz\u00f3 no obstante que los sindicatos desconvocar\u00e1n la huelga anunciada. En declaraciones a los medios, el portavoz\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/12\/ibexpress-300x146.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":6623,"url":"https:\/\/www.palmacentro.com\/blog\/huelga-de-iberia-del-18-al-22-de-febrero\/","url_meta":{"origin":5997,"position":2},"title":"Huelga de Iberia del 18 al 22 de febrero","author":"Ver\u00f3nica","date":"17\/02\/2013","format":false,"excerpt":"Los 20.000 trabajadores de Iberia est\u00e1n convocados del 18\u00a0 al\u00a0 22 de febrero a la huelga m\u00e1s importante de la compa\u00f1\u00eda, con cinco jornadas\u00a0 seguidas de paro. Est\u00e1n llamados a\u00a0 huelga\u00a0 tanto los trabajadores de vuelo como los de tierra\u00a0 y tambi\u00e9n afectar\u00e1 a algunas compa\u00f1\u00edas a los que presta\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"iberia_huelga febrero","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2013\/02\/iberia_huelga-febrero.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":1510,"url":"https:\/\/www.palmacentro.com\/blog\/iberia-anulara-vuelos-este-lunes\/","url_meta":{"origin":5997,"position":3},"title":"Iberia anular\u00e1 vuelos este lunes","author":"Ver\u00f3nica","date":"19\/02\/2012","format":false,"excerpt":"La aerol\u00ednea Iberia anular\u00e1 153 enlaces el lunes 20 de febrero con motivo de la d\u00e9cima jornada de huelga convocada por la secci\u00f3n sindical de Sepla en la aerol\u00ednea en protesta por la creaci\u00f3n de Express. Fomento ha establecido como servicios m\u00ednimos todos los vuelos entre la Pen\u00ednsula y las\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/02\/iberia_huelga_pilotos_0.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/02\/iberia_huelga_pilotos_0.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/02\/iberia_huelga_pilotos_0.jpg?resize=525%2C300 1.5x"},"classes":[]},{"id":6693,"url":"https:\/\/www.palmacentro.com\/blog\/vibo-cierra-todas-sus-agencias-de-viaje\/","url_meta":{"origin":5997,"position":4},"title":"Vibo cierra todas sus agencias de viaje","author":"Ver\u00f3nica","date":"21\/02\/2013","format":false,"excerpt":"Orizonia ha dado orden de cierre al p\u00fablico de todas las agencias Vibo Viajes (antiguo Viajes Iberia)\u00a0 a partir de hoy\u00a0 jueves 21 de febrero, hasta aclarar la situaci\u00f3n en que se encuentra debido al preconcurso de acreedores. Alrededor de 950 agencias que posee Vibo entre\u00a0 Espa\u00f1a y Portugal cerrar\u00e1n\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"1_Vibo","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2013\/02\/1_Vibo-300x205.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":5734,"url":"https:\/\/www.palmacentro.com\/blog\/los-sindicatos-invitan-a-parados-y-trabajadores-a-participar-en-el-14n\/","url_meta":{"origin":5997,"position":5},"title":"Los Sindicatos invitan a parados y trabajadores a participar en el 14N","author":"Ver\u00f3nica","date":"13\/11\/2012","format":false,"excerpt":"Representantes de CCOO, UGT, STEI-i y USO han acudido hoy a la oficina del SOIB de Palma para informar a los desempleados de que pueden secundar la huelga general de ma\u00f1ana dejando de consumir y evitando realizar tr\u00e1mites administrativos, entre otras acciones. CCOO quiere que los parados tomen conciencia de\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/11\/HG14-N_todos_manos.jpg?resize=350%2C200","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/posts\/5997","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/comments?post=5997"}],"version-history":[{"count":1,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/posts\/5997\/revisions"}],"predecessor-version":[{"id":5999,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/posts\/5997\/revisions\/5999"}],"wp:attachment":[{"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/media?parent=5997"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/categories?post=5997"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/tags?post=5997"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}