{"id":6986,"date":"2013-04-08T14:12:16","date_gmt":"2013-04-08T12:12:16","guid":{"rendered":"http:\/\/www.palmacentro.com\/blog\/?p=6986"},"modified":"2013-04-08T14:13:11","modified_gmt":"2013-04-08T12:13:11","slug":"abierto-el-plazo-de-adscripcion-para-el-nuevo-curso","status":"publish","type":"post","link":"https:\/\/www.palmacentro.com\/blog\/abierto-el-plazo-de-adscripcion-para-el-nuevo-curso\/","title":{"rendered":"Abierto el plazo de inscripci\u00f3n para el nuevo curso"},"content":{"rendered":"\n<!-- Speed Sense for AdSense WordPress Plugin: https:\/\/wordpress.org\/plugins\/speed-sense\/ -->\n<div id=\"ssp0\" style=\"float:none;margin:10px 0 10px 0;text-align:center;max-width:728px;width:100%;\">\n<ins class=\"adsbygoogle\" id=\"adsgoogle0\" style=\"display: inline-block; width: 100%; height: 90px\"  data-ad-client=\"ca-pub-8118652243852059\" data-ad-slot=\"7814439714\"><\/ins><script>(adsbygoogle = window.adsbygoogle || []).push({});<\/script>\n<\/div>\n<p><a href=\"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2013\/04\/matricula-colegio.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"6987\" data-permalink=\"https:\/\/www.palmacentro.com\/blog\/abierto-el-plazo-de-adscripcion-para-el-nuevo-curso\/matricula-colegio\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2013\/04\/matricula-colegio.jpg?fit=400%2C300&amp;ssl=1\" data-orig-size=\"400,300\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"matricula colegio\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2013\/04\/matricula-colegio.jpg?fit=400%2C300&amp;ssl=1\" class=\"aligncenter size-full wp-image-6987\" alt=\"matricula colegio\" src=\"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2013\/04\/matricula-colegio.jpg?resize=351%2C264\" width=\"351\" height=\"264\" srcset=\"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2013\/04\/matricula-colegio.jpg?w=400&amp;ssl=1 400w, https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2013\/04\/matricula-colegio.jpg?resize=300%2C225&amp;ssl=1 300w\" sizes=\"auto, (max-width: 351px) 100vw, 351px\" \/><\/a><\/p>\n<p>Empieza el <strong>proceso de inscripci\u00f3n del pr\u00f3ximo curso<\/strong>, que afecta sobretodo a los alumnos que deben cambiar de centro como los de Infantil y de Primaria.<\/p>\n<p>Alrededor de 12.177 ni\u00f1os de tres a\u00f1os\u00a0 se matricular\u00e1n por primera vez en los centros educativos de la comunidad, por lo que el Govern calcula que ser\u00e1n unos 10.677 quienes lo har\u00e1n en colegios sostenidos con fondos p\u00fablicos. Una de las novedades de \u00e9ste a\u00f1os ser\u00e1n las solicitudes de forma <strong>telem\u00e1tica<\/strong> que se podr\u00e1n realizar para <strong>Infantil, Primaria y ESO,<\/strong> y as\u00ed evitar que los padres tengan que desplazarse a los centros u oficinas de escolarizaci\u00f3n.<!--more-->El proceso de admisi\u00f3n para los alumnos de Educaci\u00f3n Infantil, Primaria y ESO empieza el d\u00eda 2 de mayo hasta el 16 del mismo mes. El 5 de junio se publicar\u00e1n las listas provisionales de admitidos y as\u00ed del 14 al 26 de junio comenzar\u00e1 la matriculaci\u00f3n de Infantil y Primaria, y del 4 al 8 de julio la matriculaci\u00f3n de ESO.<\/p>\n<p>Para los alumnos de Bachillerato se iniciar\u00e1n los tramites el 24 de junio hasta el 26 de junio. El 4 de julio se publicar\u00e1n las listas provisionales de admitidos y el d\u00eda 11 las definitivas. El periodo de matriculaci\u00f3n ser\u00e1 del 15 al 17 de julio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Empieza el proceso de inscripci\u00f3n del pr\u00f3ximo curso, que afecta sobretodo a los alumnos que deben cambiar de centro como[&#8230;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[2015,5017,5022,5020,91,904,5019,813,1329,470,1143,5021,37,1810,5018,1943],"class_list":["post-6986","post","type-post","status-publish","format-standard","hentry","category-eventos-noticias","tag-2015","tag-5017","tag-admitidos","tag-bachillerato","tag-colegio","tag-curso","tag-eso","tag-infantil","tag-inscripcion","tag-instituto","tag-internet","tag-listas","tag-mallorca","tag-matricula","tag-matriculacion","tag-primaria"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p1SDLj-1OG","jetpack-related-posts":[{"id":3055,"url":"https:\/\/www.palmacentro.com\/blog\/hoy-es-el-ultimo-dia-para-pedir-plaza-en-el-colegio\/","url_meta":{"origin":6986,"position":0},"title":"Hoy es el \u00faltimo d\u00eda para pedir plaza en el colegio","author":"PalmaCentro","date":"28\/05\/2012","format":false,"excerpt":"Hoy concluye el periodo para que los alumnos de Infantil, Primaria y Secundaria pidan plaza en los colegios de las islas, en un proceso en el que alrededor de 50.000 ni\u00f1os de entre tres y siete a\u00f1os han tenido la posibilidad de escoger la primera lengua de su ense\u00f1anza durante\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/05\/colegio1.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/05\/colegio1.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/05\/colegio1.jpg?resize=525%2C300 1.5x"},"classes":[]},{"id":1155,"url":"https:\/\/www.palmacentro.com\/blog\/curso-de-japones-en-palma\/","url_meta":{"origin":6986,"position":1},"title":"Curso de Japon\u00e9s en Palma","author":"PalmaCentro","date":"07\/02\/2012","format":false,"excerpt":"Hola! Os recuerdo que el pr\u00f3ximo Lunes d\u00eda 13 de Febrero empieza nuestro CURSO DE JAPON\u00c9S PARA PRINCIPIANTES, los interesados ten\u00e9is hasta el pr\u00f3ximo Viernes 10 de Febrero para hacer la inscripci\u00f3n. Para ello deb\u00e9is acudir a C\/\u00a0Jeroni Rossell\u00f3 21 para rellenar la inscripci\u00f3n y pagar los 150 Euros del\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/01\/curso_japones-206x300.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":2649,"url":"https:\/\/www.palmacentro.com\/blog\/ya-estan-disponibles-las-hojas-para-elegir-la-lengua-de-educacion-de-los-hijos\/","url_meta":{"origin":6986,"position":2},"title":"Ya estan disponibles las hojas para elegir la lengua de educaci\u00f3n de los hijos","author":"Ver\u00f3nica","date":"09\/05\/2012","format":false,"excerpt":"Los colegios p\u00fablicos y concertados de Baleares ya disponen de las nuevas hojas de escolarizaci\u00f3n. Ahora\u00a0 tenemos la posibilidad de elegir la lengua de educaci\u00f3n de nuestros hijos. Por primera vez , se incluye un apartado con dos casillas, una para catal\u00e1n y otra para castellano. Ya se puede ir\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/05\/colegio-300x198.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":6450,"url":"https:\/\/www.palmacentro.com\/blog\/xviii-concurso-infantil-de-disfraces\/","url_meta":{"origin":6986,"position":3},"title":"XVIII Concurso Infantil de disfraces","author":"Ver\u00f3nica","date":"31\/01\/2013","format":false,"excerpt":"Concurso de Carnaval en El Corte Ingl\u00e9s con la colaboraci\u00f3n de Diario de Mallorca\u00a0 del 2 al 9 de febrero en la Planta \u00c1tico de El Corte Ingl\u00e9s Avenidas. Pueden participar los ni\u00f1@s menores de 14 a\u00f1os, pudiendo presentarse tambi\u00e9n en grupo. Los d\u00edas del concurso son; 2 de febrero\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"concurso disfraces corte ingles","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2013\/01\/concurso-disfraces-corte-ingles.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":3219,"url":"https:\/\/www.palmacentro.com\/blog\/660-plazas-para-los-campamentos-de-verano-para-ninos-y-jovenes-de-8-a-17-anos\/","url_meta":{"origin":6986,"position":4},"title":"660 plazas para los campamentos de verano para ni\u00f1os y j\u00f3venes de 8 a 17 a\u00f1os","author":"Ver\u00f3nica","date":"05\/06\/2012","format":false,"excerpt":"La regidora de Comercio, Trabajo y Juventud, Esperanza Cresp\u00ed, ha presentado la campa\u00f1a de Campamentos de Verano 2012 que este a\u00f1o oferta 660 plazas en el Campamento La Victoria para ni\u00f1os y j\u00f3venes de 8 a 17 a\u00f1os empadronados en Palma. El Ayuntamiento ha reservado el 15% de las plazas\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/06\/Captura.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":1761,"url":"https:\/\/www.palmacentro.com\/blog\/los-banos-del-colegio-del-rafal-vell-en-mal-estado\/","url_meta":{"origin":6986,"position":5},"title":"Los ba\u00f1os del colegio del Rafal Vell, en mal estado.","author":"Ver\u00f3nica","date":"12\/03\/2012","format":false,"excerpt":"Los ba\u00f1os del colegio de educaci\u00f3n infantil y primaria de Rafal Vell se encuentran en mal estado y acumulan suciedad desde hace a\u00f1os. Por ese motivo la Asociaci\u00f3n de Madres y Padres de Alumnos (AMPA) de este centro educativo, apoyada por los profesores y la direcci\u00f3n, ha iniciado una campa\u00f1a\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/03\/ba%C3%B1os-300x141.jpg?resize=350%2C200","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/posts\/6986","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/comments?post=6986"}],"version-history":[{"count":2,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/posts\/6986\/revisions"}],"predecessor-version":[{"id":6989,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/posts\/6986\/revisions\/6989"}],"wp:attachment":[{"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/media?parent=6986"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/categories?post=6986"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/tags?post=6986"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}