{"id":7342,"date":"2013-06-19T18:39:37","date_gmt":"2013-06-19T16:39:37","guid":{"rendered":"http:\/\/www.palmacentro.com\/blog\/?p=7342"},"modified":"2013-06-19T18:47:35","modified_gmt":"2013-06-19T16:47:35","slug":"autoservicio-gratuito-para-facilitar-las-gestiones-municipales","status":"publish","type":"post","link":"https:\/\/www.palmacentro.com\/blog\/autoservicio-gratuito-para-facilitar-las-gestiones-municipales\/","title":{"rendered":"Autoservicio gratuito para facilitar las gestiones municipales"},"content":{"rendered":"\n<!-- Speed Sense for AdSense WordPress Plugin: https:\/\/wordpress.org\/plugins\/speed-sense\/ -->\n<div id=\"ssp0\" style=\"float:none;margin:10px 0 10px 0;text-align:center;max-width:728px;width:100%;\">\n<ins class=\"adsbygoogle\" id=\"adsgoogle0\" style=\"display: inline-block; width: 100%; height: 90px\"  data-ad-client=\"ca-pub-8118652243852059\" data-ad-slot=\"7814439714\"><\/ins><script>(adsbygoogle = window.adsbygoogle || []).push({});<\/script>\n<\/div>\n<p style=\"text-align: center;\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"7343\" data-permalink=\"https:\/\/www.palmacentro.com\/blog\/autoservicio-gratuito-para-facilitar-las-gestiones-municipales\/0_70734_1\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2013\/06\/0_70734_1.jpg?fit=240%2C361&amp;ssl=1\" data-orig-size=\"240,361\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"autoservei\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2013\/06\/0_70734_1.jpg?fit=240%2C361&amp;ssl=1\" class=\"aligncenter size-full wp-image-7343\" alt=\"autoservei\" src=\"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2013\/06\/0_70734_1.jpg?resize=197%2C297\" width=\"197\" height=\"297\" srcset=\"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2013\/06\/0_70734_1.jpg?w=240&amp;ssl=1 240w, https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2013\/06\/0_70734_1.jpg?resize=199%2C300&amp;ssl=1 199w\" sizes=\"auto, (max-width: 197px) 100vw, 197px\" \/><\/p>\n<p>La<strong> Oficina de Atenci\u00f3n al Ciudadano<\/strong> ubicada en las dependencias de la Polic\u00eda Local en Sant Ferran, ha incorporado un punto de <strong>autoservicio electr\u00f3nico<\/strong> a trav\u00e9s del cual los ciudadanos pueden realizar de forma totalmente gratuita <strong>diferentes gestiones municipales sin tener esperar a las diferentes oficinas municipales.<\/strong><\/p>\n<p>Ahora, los ciudadanos pueden acceder a los <strong>siguientes servicios:<\/strong><\/p>\n<p>&#8211; Pago de multas con notificaci\u00f3n<br \/>\n&#8211; Pago de sanciones de tr\u00e1fico y denuncias de ORA con bolet\u00edn<br \/>\n&#8211; Obtenci\u00f3n de certificados de residencia para viajes<!--more--><br \/>\n&#8211; Solicitud de cita previa: altas y modificaciones en el Padr\u00f3n municipal<br \/>\n&#8211; Informaci\u00f3n sobre tr\u00e1mites del Padr\u00f3n de habitantes<br \/>\n&#8211; Informaci\u00f3n sobre la ORA<br \/>\n&#8211; Informaci\u00f3n sobre la ACIRE<br \/>\n&#8211; Tabl\u00f3n de edictos y anuncios<\/p>\n<p>Dentro de la filosof\u00eda de <strong>SmartCity<\/strong>, el objetivo \u00faltimo de la cual es hacer de Palma una ciudad sostenible y moderna, facilitando el acceso del ciudadano a la Administraci\u00f3n p\u00fablica, Corte da un paso m\u00e1s hacia la modernizaci\u00f3n y adaptaci\u00f3n del servicio p\u00fablico a las nuevas tecnolog\u00edas y ampliar\u00e1 este punto de autoservicio electr\u00f3nico a las oficinas municipales que suelen concentrar una mayor afluencia de ciudadanos.<\/p>\n<p>Via\/<a href=\"http:\/\/www.palmademallorca.es\/portal\/PALMA\/contenedor1.jsp?seccion=s_fnot_d4_v1.jsp&amp;contenido=70729&amp;tipo=8&amp;nivel=1400&amp;layout=contenedor1.jsp&amp;codResi=1&amp;language=ca\">AjPalma<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Oficina de Atenci\u00f3n al Ciudadano ubicada en las dependencias de la Polic\u00eda Local en Sant Ferran, ha incorporado un[&#8230;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[5178,5181,5176,523,5177,5182,5183,788,5180,5179,5601],"class_list":["post-7342","post","type-post","status-publish","format-standard","hentry","category-eventos-noticias","tag-autoservicio","tag-certificado-residencia","tag-gestiones","tag-multas","tag-municipales","tag-oac","tag-oficina","tag-ora","tag-padron","tag-pagos","tag-palma"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p1SDLj-1Uq","jetpack-related-posts":[{"id":4716,"url":"https:\/\/www.palmacentro.com\/blog\/los-certificados-de-residente-digitales-y-de-los-cajeros-si-son-validos\/","url_meta":{"origin":7342,"position":0},"title":"Los certificados de residente digitales y de cajeros si son v\u00e1lidos","author":"Ver\u00f3nica","date":"04\/09\/2012","format":false,"excerpt":"El Ministerio de Fomento ha enviado un comunicado a las aerol\u00edneas notific\u00e1ndoles que tienen que aceptar los certificados de residente expedidos a trav\u00e9s de las p\u00e1ginas web de los ayuntamientos o de los cajeros de Sa Nostra y la Caixa a las personas que viajan con descuento; as\u00ed como que\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/09\/tarjeta-embarque1.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":2317,"url":"https:\/\/www.palmacentro.com\/blog\/en-baleares-aumentan-los-empadronados-con-5-540-personas-mas\/","url_meta":{"origin":7342,"position":1},"title":"En Baleares aumentan los empadronados con 5.540 personas m\u00e1s","author":"Ver\u00f3nica","date":"19\/04\/2012","format":false,"excerpt":"Los residentes en Balears ya sumaban 1.118.654 personas en enero de 2012, lo que supone un aumento de 5.540 ciudadanos respecto a un a\u00f1o antes, seg\u00fan datos del Instituto Nacional de Estad\u00edstica (INE). Del total de personas empadronadas en Baleares, el 21,6 % son extranjeros, 242.138 personas en el padr\u00f3n\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/04\/14876-406-304.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":1797,"url":"https:\/\/www.palmacentro.com\/blog\/inca-recupera-el-servicio-de-ora-en-las-calles-del-centro\/","url_meta":{"origin":7342,"position":2},"title":"Inca recupera el servicio de ORA en las calles del centro","author":"Ver\u00f3nica","date":"14\/03\/2012","format":false,"excerpt":"El Ayuntamiento de Inca impulsa de nuevo el sistema de rotaci\u00f3n de aparcamiento ORA que se implantar\u00e1 en las calles m\u00e1s c\u00e9ntricas de la ciudad este a\u00f1o 2012 y que tiene el objetivo de dinamizar los comercios del centro. Seg\u00fan Torres \u00abel sistema ORA propiciar\u00e1 a que las personas puedan\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/03\/ora-300x141.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":2696,"url":"https:\/\/www.palmacentro.com\/blog\/el-ayuntamiento-mas-cerca-de-la-administracion-electronica\/","url_meta":{"origin":7342,"position":3},"title":"El Ayuntamiento mas cerca de la administraci\u00f3n electr\u00f3nica","author":"Ver\u00f3nica","date":"10\/05\/2012","format":false,"excerpt":"El certificado de residente se podr\u00e1 obtener de forma inminente y gratuita a trav\u00e9s de internet, ya que la Junta de Gobierno aprob\u00f3 la creaci\u00f3n de la sede electr\u00f3nica. Esta medida estar\u00e1 en funcionamiento en una semana o diez d\u00edas. El portavoz del equipo de gobierno, Julio Mart\u00ednez, explic\u00f3 que\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/05\/Captura3.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":4051,"url":"https:\/\/www.palmacentro.com\/blog\/els-3-tenors-en-el-auditorium-sa-maniga\/","url_meta":{"origin":7342,"position":4},"title":"Els 3 Tenors en el Auditorium sa M\u00e0niga","author":"Ver\u00f3nica","date":"24\/07\/2012","format":false,"excerpt":"El dia 27 de julio a las 21:30 h en el Audit\u00f2rium de sa M\u00e0niga tendremos la representaci\u00f3n de LOS TRES TENORES. Tres de los mejores tenores espa\u00f1oles que trabajan actualmente en los grandes teatros de \u00f3pera como el Liceu de Barcelona o las Artes de Valencia cantan arias de\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/07\/3-tenorios.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":1971,"url":"https:\/\/www.palmacentro.com\/blog\/informacion-publica-de-la-ordenanza-municipal-de-ocupacion-de-via-publica\/","url_meta":{"origin":7342,"position":5},"title":"Informaci\u00f3n p\u00fablica de la ordenanza municipal de ocupaci\u00f3n de v\u00eda p\u00fablica","author":"Ver\u00f3nica","date":"27\/03\/2012","format":false,"excerpt":"Aqu\u00ed os dejo algunas de las ordenanzas municipales publicadas en el BOIB n\u00ba 39 del 15\/03\/2012 Las ocupaciones realizadas por bares, cafeter\u00edas y restaurantes deber\u00e1n cumplir las prescripciones recogidas en el documento tales como: -Periodo m\u00ednimo autorizable ser\u00e1 de 3 meses continuos. -El espacio que quede libre a la acera\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/03\/delimitar-bar.jpg?resize=350%2C200","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/posts\/7342","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/comments?post=7342"}],"version-history":[{"count":3,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/posts\/7342\/revisions"}],"predecessor-version":[{"id":7345,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/posts\/7342\/revisions\/7345"}],"wp:attachment":[{"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/media?parent=7342"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/categories?post=7342"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/tags?post=7342"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}