{"id":7374,"date":"2013-07-01T18:14:21","date_gmt":"2013-07-01T16:14:21","guid":{"rendered":"http:\/\/www.palmacentro.com\/blog\/?p=7374"},"modified":"2013-07-01T18:14:21","modified_gmt":"2013-07-01T16:14:21","slug":"programacion-blue-jazz-club-para-julio-2013","status":"publish","type":"post","link":"https:\/\/www.palmacentro.com\/blog\/programacion-blue-jazz-club-para-julio-2013\/","title":{"rendered":"Programaci\u00f3n Blue Jazz Club para Julio 2013"},"content":{"rendered":"\n<!-- Speed Sense for AdSense WordPress Plugin: https:\/\/wordpress.org\/plugins\/speed-sense\/ -->\n<div id=\"ssp0\" style=\"float:none;margin:10px 0 10px 0;text-align:center;max-width:728px;width:100%;\">\n<ins class=\"adsbygoogle\" id=\"adsgoogle0\" style=\"display: inline-block; width: 100%; height: 90px\"  data-ad-client=\"ca-pub-8118652243852059\" data-ad-slot=\"7814439714\"><\/ins><script>(adsbygoogle = window.adsbygoogle || []).push({});<\/script>\n<\/div>\n<p><a href=\"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2013\/07\/BLUE-JAZZ-CLUB.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"7375\" data-permalink=\"https:\/\/www.palmacentro.com\/blog\/programacion-blue-jazz-club-para-julio-2013\/blue-jazz-club\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2013\/07\/BLUE-JAZZ-CLUB.jpg?fit=425%2C297&amp;ssl=1\" data-orig-size=\"425,297\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"BLUE JAZZ CLUB\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2013\/07\/BLUE-JAZZ-CLUB.jpg?fit=425%2C297&amp;ssl=1\" class=\"aligncenter size-full wp-image-7375\" alt=\"BLUE JAZZ CLUB\" src=\"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2013\/07\/BLUE-JAZZ-CLUB.jpg?resize=320%2C224\" width=\"320\" height=\"224\" srcset=\"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2013\/07\/BLUE-JAZZ-CLUB.jpg?w=425&amp;ssl=1 425w, https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2013\/07\/BLUE-JAZZ-CLUB.jpg?resize=300%2C209&amp;ssl=1 300w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/><\/a><\/p>\n<p>Programaci\u00f3n para el mes de <strong>Julio en el Blue Jazz Club<\/strong> ubicado en el Hotel Saratoga de Palma. La entrada es gratuita.<\/p>\n<p><a href=\"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2013\/07\/julio1.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"7379\" data-permalink=\"https:\/\/www.palmacentro.com\/blog\/programacion-blue-jazz-club-para-julio-2013\/julio1\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2013\/07\/julio1.jpg?fit=642%2C482&amp;ssl=1\" data-orig-size=\"642,482\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Nika&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1372702275&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"julio1\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2013\/07\/julio1.jpg?fit=642%2C482&amp;ssl=1\" class=\"aligncenter size-full wp-image-7379\" alt=\"julio1\" src=\"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2013\/07\/julio1.jpg?resize=642%2C482\" width=\"642\" height=\"482\" srcset=\"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2013\/07\/julio1.jpg?w=642&amp;ssl=1 642w, https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2013\/07\/julio1.jpg?resize=300%2C225&amp;ssl=1 300w\" sizes=\"auto, (max-width: 642px) 100vw, 642px\" \/><\/a><!--more--><\/p>\n<p><a href=\"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2013\/07\/julio2.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"7380\" data-permalink=\"https:\/\/www.palmacentro.com\/blog\/programacion-blue-jazz-club-para-julio-2013\/julio2\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2013\/07\/julio2.jpg?fit=642%2C381&amp;ssl=1\" data-orig-size=\"642,381\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Nika&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1372702304&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"julio2\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2013\/07\/julio2.jpg?fit=642%2C381&amp;ssl=1\" class=\"aligncenter size-full wp-image-7380\" alt=\"julio2\" src=\"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2013\/07\/julio2.jpg?resize=642%2C381\" width=\"642\" height=\"381\" srcset=\"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2013\/07\/julio2.jpg?w=642&amp;ssl=1 642w, https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2013\/07\/julio2.jpg?resize=300%2C178&amp;ssl=1 300w\" sizes=\"auto, (max-width: 642px) 100vw, 642px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Programaci\u00f3n para el mes de Julio en el Blue Jazz Club ubicado en el Hotel Saratoga de Palma. La entrada[&#8230;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[2015,4185,1181,2845,2128,37,5601,2455,4186],"class_list":["post-7374","post","type-post","status-publish","format-standard","hentry","category-eventos-noticias","tag-2015","tag-blue-jazz-club","tag-hotel","tag-jazz","tag-julio","tag-mallorca","tag-palma","tag-programacion","tag-saratoga"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p1SDLj-1UW","jetpack-related-posts":[{"id":5574,"url":"https:\/\/www.palmacentro.com\/blog\/blue-jazz-club-programacion-noviembre\/","url_meta":{"origin":7374,"position":0},"title":"Blue Jazz Club &#8211; Programaci\u00f3n noviembre","author":"Ver\u00f3nica","date":"04\/11\/2012","format":false,"excerpt":"\"Blue Jazz Club\", es un espacio que cuenta con la presencia de artistas de jazz todos los jueves, viernes y s\u00e1bados de las 23 horas a la una de la madrugada en el Hotel Saratoga de Palma. Los asistentes podr\u00e1n disfrutar de actuaciones en directo por parte de grupos de\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/10\/blue_jazz_club_logo.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":3980,"url":"https:\/\/www.palmacentro.com\/blog\/conciertos-de-la-semana-del-23-al-29-de-julio\/","url_meta":{"origin":7374,"position":1},"title":"Conciertos de la semana: del 23 al 29 de julio","author":"Ver\u00f3nica","date":"23\/07\/2012","format":false,"excerpt":"\u00a0 Aqu\u00ed ten\u00e9is una serie de conciertos de la semana del 23 al 29 de julio en el que la mayor\u00eda son gratuitos as\u00ed que no hay escusa para disfrutar de un buen concierto tom\u00e1ndose unas copas. Lunes 23 23:55 h. Concierto de El Barrendero del Blues en el Bluesville,\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/07\/CONCIERTOS.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":4466,"url":"https:\/\/www.palmacentro.com\/blog\/wonderbrass-actuara-en-el-blue-jazz-club-del-hotel-saratoga\/","url_meta":{"origin":7374,"position":2},"title":"WonderBrass actuar\u00e1 en el Blue Jazz Club del Hotel Saratoga","author":"Ver\u00f3nica","date":"21\/08\/2012","format":false,"excerpt":"El jueves 23 de agosto a partir de las 22h, WonderBrass actuar\u00e1 en el Blue Jazz Club del Hotel Saratoga. Carcajadas a ritmo de swing. Wonderbrass nace en la isla de Mallorca en 1999, sus cuatro miembros: N\u00e9stor Casas (trompeta y voz), Nacho Vegas (saxo tenor, clarinete, guitarra, voz), Didac\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2012\/08\/jazzclub-54_3.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":8673,"url":"https:\/\/www.palmacentro.com\/blog\/soul-cafe-actuara-el-31-de-enero-en-el-blue-jazz-club-de-palma\/","url_meta":{"origin":7374,"position":3},"title":"Soul Caf\u00e9 actuar\u00e1 el 31 de Enero en el Blue Jazz Club de Palma","author":"Ver\u00f3nica","date":"19\/01\/2015","format":false,"excerpt":"Soul Caf\u00e9 actuar\u00e1 el 31 de enero a las 23h en el Blue Jazz Club de Palma de Mallorca (Hotel Saratoga). Entrada gratuita. Soul Caf\u00e9 es una banda cl\u00e1sica fundada a mediados de los '90, el grupo ha ido ampliando su repertorio bailable m\u00e1s tradicional (los cl\u00e1sicos del sonido \"Motown\"\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"(c) Alex Cooper ","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2015\/01\/133478_10151413739633835_690648179_o-1024x503.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":6906,"url":"https:\/\/www.palmacentro.com\/blog\/mallorca-saxophone-festival-del-22-al-27-de-marzo\/","url_meta":{"origin":7374,"position":4},"title":"Mallorca Saxophone Festival del 22 al 27 de marzo","author":"Ver\u00f3nica","date":"22\/03\/2013","format":false,"excerpt":"La 5\u00aa edici\u00f3n del Mallorca Saxophone Festival ser\u00e1 del 22 al 27 de marzo, organitzada por la Associaci\u00f3 de Saxofonistes de les Illes Balears, con la colaboraci\u00f3n del Institut d\u2019Estudis Bale\u00e0rics (IEB). Aqu\u00ed est\u00e1 la programaci\u00f3n de los conciertos del festival de saxof\u00f3n de Mallorca que se realizar\u00e1n en diversos\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"saxophonemallorca2013","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2013\/03\/saxophonemallorca20131.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":7508,"url":"https:\/\/www.palmacentro.com\/blog\/cinema-a-la-fresca-en-le-parc-de-la-mar-programacion-julio\/","url_meta":{"origin":7374,"position":5},"title":"Cinema a la Fresca en el Parc de la Mar &#8211; Programaci\u00f3n Julio","author":"Ver\u00f3nica","date":"23\/07\/2013","format":false,"excerpt":"La temporada de \"Cinema a la Fresa\" ya ha empezado, como cada a\u00f1o pod\u00e9is disfrutar de una serie de pel\u00edculas gratuitas que se proyectan en el Parc de la Mar de Palma. Los pr\u00f3ximos pases son los siguientes: \u00a0 Mi\u00e9rcoles 24 de julio a las 22h El ladr\u00f3n de las\u2026","rel":"","context":"En \u00abEventos y Noticias\u00bb","block_context":{"text":"Eventos y Noticias","link":"https:\/\/www.palmacentro.com\/blog\/category\/eventos-noticias\/"},"img":{"alt_text":"cinema a la fresca","src":"https:\/\/i0.wp.com\/www.palmacentro.com\/blog\/wp-content\/uploads\/2013\/07\/cinema-a-la-fresca-144x300.jpg?resize=350%2C200","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/posts\/7374","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/comments?post=7374"}],"version-history":[{"count":4,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/posts\/7374\/revisions"}],"predecessor-version":[{"id":7381,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/posts\/7374\/revisions\/7381"}],"wp:attachment":[{"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/media?parent=7374"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/categories?post=7374"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/tags?post=7374"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}