{"id":3091,"count":1,"description":"","link":"https:\/\/www.palmacentro.com\/blog\/tag\/teniente-alcale\/","name":"teniente alcale","slug":"teniente-alcale","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/tags\/3091","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.palmacentro.com\/blog\/wp-json\/wp\/v2\/posts?tags=3091"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}